{"id":7328,"date":"2024-10-14T11:12:12","date_gmt":"2024-10-14T16:12:12","guid":{"rendered":"https:\/\/foreverfutbol.com.ec\/radio\/?p=7328"},"modified":"2024-10-14T11:12:13","modified_gmt":"2024-10-14T16:12:13","slug":"un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos","status":"publish","type":"post","link":"https:\/\/foreverfutbol.com.ec\/radio\/social\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\/","title":{"rendered":"Un nuevo mundo es posible si se aplicamos la simbiosis y no la lucha entre ciudadanos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un nuevo mundo es posible si se aplicamos la simbiosis y no la lucha entre ciudadanos.<br>Si recuperamos la conciencia y la cooperaci\u00f3n entre todos. Tal como lo propuso el pr\u00edncipe ruso Piotr Aleks\u00e9yevich Kropotkin (1842-1921) en la \u00e9poca del auge del Darwinismo y de la Revoluci\u00f3n Bolchevique en 1917, afirm\u00f3 en su libro EL APOYO MUTUO que \u00abla naturaleza funciona cuando hay cooperaci\u00f3n y no por la lucha\u00bb. Este pensador en espa\u00f1ol es conocido como Pedro Kropotkin, quien adem\u00e1s fue ge\u00f3grafo, zo\u00f3logo y naturalista, junto con ser te\u00f3rico pol\u00edtico y econ\u00f3mico, escritor y gran pensador. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veamos que si en Ecuador tenemos una Constituci\u00f3n redactada para favorecer la lucha de clases como fue y sigue siendo la consigna marxista, es obvio que el campo que promueve esa constituci\u00f3n no es el m\u00e1s adecuado para desarrollar al Ecuador. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Actualmente, los cient\u00edficos han demostrado que la evoluci\u00f3n sucede gracias a la cooperaci\u00f3n entre los organismos m\u00e1s que por la pugna, la prohibici\u00f3n, la depredaci\u00f3n y el parasitismo. Estas \u00faltimas matan, agreden, reivindican a trav\u00e9s de la fuerza, y quitan, dividen y restan, mientras la cooperaci\u00f3n es la simbiosis que pone, suma y multiplica. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Biolog\u00eda se estudia la simbiosis como la asociaci\u00f3n de individuos animales o vegetales de diferentes especies, sobre todo si los simbiontes sacan provecho de la vida en com\u00fan. La simbiosis es sin\u00f3nimo de asociaci\u00f3n, uni\u00f3n, v\u00ednculo. Cualidades que hacen funcionar a los grupos humanos, comenzando con la familia, el barrio, la ciudad, la provincia y como resultado final un pa\u00eds. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La simbiosis, entonces, hace que los humanos como cualquiera de las especies, aunque puedan ser diferentes entre ellas, salen beneficiadas mutuamente para construir un ambiente mejor. \u00bfPor qu\u00e9 los humanos o ciertos humanos no aplican la cooperaci\u00f3n para un mundo mejor? <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Porque no hay conciencia personal o social. Porque alguien se ha encargado de anularla.<br>Cada vez es m\u00e1s imprescindible educar a los j\u00f3venes para que cambien el mundo. Siempre que refuercen su conciencia individual de generosidad y eliminen el ego\u00edsmo, tendr\u00e1n una conciencia colectiva mejor. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con una mejor educaci\u00f3n se asegura el conocimiento, el mejoramiento cultural sobre lo material.<br>Si hoy algunos j\u00f3venes caen en la tentaci\u00f3n del dinero f\u00e1cil a trav\u00e9s del micro tr\u00e1fico de drogas, el sicariato, el secuestro y la vacuna es porque han priorizado el dinero sobre la vida de los dem\u00e1s. Han perdido la conciencia del respeto a la vida y que alg\u00fan d\u00eda deber\u00e1n rendir cuenta no s\u00f3lo a la sociedad, sino a Dios. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es el conocimiento de la realidad y del amor a la libertad la que nos hace valorar la moral y la \u00e9tica, por eso tiene vigencia eterna la cita b\u00edblica de Jes\u00fas: \u00abla verdad os har\u00e1 libres\u00bb. En definitiva, la simbiosis es la alternativa a la lucha de clases. Kropotkin demostr\u00f3 que ten\u00eda raz\u00f3n, aunque demor\u00f3 72 a\u00f1os hasta que el pueblo ruso termin\u00f3 con el marxismo y su lucha de clases. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EDITORIAL DE 92.5 FOREVER RADIO, LUNES 14 DE OCTUBRE DE 2024. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por: Washington Delgado L.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">#Ecuador #Constituci\u00f3n #EditorialForever #simbiosis <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un nuevo mundo es posible si se aplicamos la simbiosis y no la lucha entre ciudadanos.Si recuperamos la conciencia y la cooperaci\u00f3n entre todos. Tal como lo propuso el pr\u00edncipe ruso Piotr Aleks\u00e9yevich Kropotkin (1842-1921) en la \u00e9poca del auge del Darwinismo y de la Revoluci\u00f3n Bolchevique en 1917, afirm\u00f3 en su libro EL APOYO [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7261,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[],"class_list":["post-7328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-social"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un nuevo mundo es posible si se aplicamos la simbiosis y no la lucha entre ciudadanos - 92.5 FOREVER Radio<\/title>\n<meta name=\"description\" content=\"Actualmente, los cient\u00edficos han demostrado que la evoluci\u00f3n sucede gracias a la cooperaci\u00f3n entre los organismos m\u00e1s que por la pugna...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/foreverfutbol.com.ec\/radio\/social\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un nuevo mundo es posible si se aplicamos la simbiosis y no la lucha entre ciudadanos - 92.5 FOREVER Radio\" \/>\n<meta property=\"og:description\" content=\"Actualmente, los cient\u00edficos han demostrado que la evoluci\u00f3n sucede gracias a la cooperaci\u00f3n entre los organismos m\u00e1s que por la pugna...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/social\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\/\" \/>\n<meta property=\"og:site_name\" content=\"92.5 FOREVER Radio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063550693491\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-14T16:12:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-14T16:12:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/10\/Ecuador-DanielNoboa-NayibBukele-JavierMilei-GustavoPetro-TheNewYorker-EditorialForever-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"865\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ricardo Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@925forever\" \/>\n<meta name=\"twitter:site\" content=\"@925forever\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/social\\\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/social\\\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\\\/\"},\"author\":{\"name\":\"Ricardo Rodriguez\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/person\\\/2f679dd16f889ac00df6e7b648062a01\"},\"headline\":\"Un nuevo mundo es posible si se aplicamos la simbiosis y no la lucha entre ciudadanos\",\"datePublished\":\"2024-10-14T16:12:12+00:00\",\"dateModified\":\"2024-10-14T16:12:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/social\\\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\\\/\"},\"wordCount\":568,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/social\\\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Ecuador-DanielNoboa-NayibBukele-JavierMilei-GustavoPetro-TheNewYorker-EditorialForever-2.png\",\"articleSection\":[\"Social\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/social\\\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/social\\\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\\\/\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/social\\\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\\\/\",\"name\":\"Un nuevo mundo es posible si se aplicamos la simbiosis y no la lucha entre ciudadanos - 92.5 FOREVER Radio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/social\\\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/social\\\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Ecuador-DanielNoboa-NayibBukele-JavierMilei-GustavoPetro-TheNewYorker-EditorialForever-2.png\",\"datePublished\":\"2024-10-14T16:12:12+00:00\",\"dateModified\":\"2024-10-14T16:12:13+00:00\",\"description\":\"Actualmente, los cient\u00edficos han demostrado que la evoluci\u00f3n sucede gracias a la cooperaci\u00f3n entre los organismos m\u00e1s que por la pugna...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/social\\\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/social\\\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/social\\\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Ecuador-DanielNoboa-NayibBukele-JavierMilei-GustavoPetro-TheNewYorker-EditorialForever-2.png\",\"contentUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Ecuador-DanielNoboa-NayibBukele-JavierMilei-GustavoPetro-TheNewYorker-EditorialForever-2.png\",\"width\":1280,\"height\":865},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/social\\\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un nuevo mundo es posible si se aplicamos la simbiosis y no la lucha entre ciudadanos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\",\"name\":\"92.5 FOREVER Radio\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\",\"name\":\"92.5 FOREVER Radio\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-logo-forever.png\",\"contentUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-logo-forever.png\",\"width\":180,\"height\":154,\"caption\":\"92.5 FOREVER Radio\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100063550693491\",\"https:\\\/\\\/x.com\\\/925forever\",\"https:\\\/\\\/www.instagram.com\\\/radioforever925\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/person\\\/2f679dd16f889ac00df6e7b648062a01\",\"name\":\"Ricardo Rodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"caption\":\"Ricardo Rodriguez\"},\"sameAs\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\"],\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/author\\\/superdmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un nuevo mundo es posible si se aplicamos la simbiosis y no la lucha entre ciudadanos - 92.5 FOREVER Radio","description":"Actualmente, los cient\u00edficos han demostrado que la evoluci\u00f3n sucede gracias a la cooperaci\u00f3n entre los organismos m\u00e1s que por la pugna...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/foreverfutbol.com.ec\/radio\/social\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\/","og_locale":"es_ES","og_type":"article","og_title":"Un nuevo mundo es posible si se aplicamos la simbiosis y no la lucha entre ciudadanos - 92.5 FOREVER Radio","og_description":"Actualmente, los cient\u00edficos han demostrado que la evoluci\u00f3n sucede gracias a la cooperaci\u00f3n entre los organismos m\u00e1s que por la pugna...","og_url":"https:\/\/foreverfutbol.com.ec\/radio\/social\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\/","og_site_name":"92.5 FOREVER Radio","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063550693491","article_published_time":"2024-10-14T16:12:12+00:00","article_modified_time":"2024-10-14T16:12:13+00:00","og_image":[{"width":1280,"height":865,"url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/10\/Ecuador-DanielNoboa-NayibBukele-JavierMilei-GustavoPetro-TheNewYorker-EditorialForever-2.png","type":"image\/png"}],"author":"Ricardo Rodriguez","twitter_card":"summary_large_image","twitter_creator":"@925forever","twitter_site":"@925forever","twitter_misc":{"Escrito por":"Ricardo Rodriguez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/foreverfutbol.com.ec\/radio\/social\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\/#article","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/social\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\/"},"author":{"name":"Ricardo Rodriguez","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01"},"headline":"Un nuevo mundo es posible si se aplicamos la simbiosis y no la lucha entre ciudadanos","datePublished":"2024-10-14T16:12:12+00:00","dateModified":"2024-10-14T16:12:13+00:00","mainEntityOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/social\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\/"},"wordCount":568,"commentCount":0,"publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/social\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/10\/Ecuador-DanielNoboa-NayibBukele-JavierMilei-GustavoPetro-TheNewYorker-EditorialForever-2.png","articleSection":["Social"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/foreverfutbol.com.ec\/radio\/social\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/foreverfutbol.com.ec\/radio\/social\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/social\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\/","name":"Un nuevo mundo es posible si se aplicamos la simbiosis y no la lucha entre ciudadanos - 92.5 FOREVER Radio","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/social\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\/#primaryimage"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/social\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/10\/Ecuador-DanielNoboa-NayibBukele-JavierMilei-GustavoPetro-TheNewYorker-EditorialForever-2.png","datePublished":"2024-10-14T16:12:12+00:00","dateModified":"2024-10-14T16:12:13+00:00","description":"Actualmente, los cient\u00edficos han demostrado que la evoluci\u00f3n sucede gracias a la cooperaci\u00f3n entre los organismos m\u00e1s que por la pugna...","breadcrumb":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/social\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/foreverfutbol.com.ec\/radio\/social\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/social\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\/#primaryimage","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/10\/Ecuador-DanielNoboa-NayibBukele-JavierMilei-GustavoPetro-TheNewYorker-EditorialForever-2.png","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/10\/Ecuador-DanielNoboa-NayibBukele-JavierMilei-GustavoPetro-TheNewYorker-EditorialForever-2.png","width":1280,"height":865},{"@type":"BreadcrumbList","@id":"https:\/\/foreverfutbol.com.ec\/radio\/social\/un-nuevo-mundo-es-posible-si-se-aplicamos-la-simbiosis-y-no-la-lucha-entre-ciudadanos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/foreverfutbol.com.ec\/radio\/"},{"@type":"ListItem","position":2,"name":"Un nuevo mundo es posible si se aplicamos la simbiosis y no la lucha entre ciudadanos"}]},{"@type":"WebSite","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website","url":"https:\/\/foreverfutbol.com.ec\/radio\/","name":"92.5 FOREVER Radio","description":"","publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/foreverfutbol.com.ec\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization","name":"92.5 FOREVER Radio","url":"https:\/\/foreverfutbol.com.ec\/radio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","width":180,"height":154,"caption":"92.5 FOREVER Radio"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063550693491","https:\/\/x.com\/925forever","https:\/\/www.instagram.com\/radioforever925\/"]},{"@type":"Person","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01","name":"Ricardo Rodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","caption":"Ricardo Rodriguez"},"sameAs":["https:\/\/foreverfutbol.com.ec\/radio"],"url":"https:\/\/foreverfutbol.com.ec\/radio\/author\/superdmin\/"}]}},"_links":{"self":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/7328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/comments?post=7328"}],"version-history":[{"count":1,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/7328\/revisions"}],"predecessor-version":[{"id":7329,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/7328\/revisions\/7329"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media\/7261"}],"wp:attachment":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media?parent=7328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/categories?post=7328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/tags?post=7328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}