{"id":7304,"date":"2024-10-10T18:03:33","date_gmt":"2024-10-10T23:03:33","guid":{"rendered":"https:\/\/foreverfutbol.com.ec\/radio\/?p=7304"},"modified":"2024-10-10T18:03:33","modified_gmt":"2024-10-10T23:03:33","slug":"fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales","status":"publish","type":"post","link":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\/","title":{"rendered":"Fiscal\u00eda de Bolivia anuncia orden de aprehensi\u00f3n contra Evo Morales"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Fiscal\u00eda de Bolivia anuncia orden de aprehensi\u00f3n contra  Evo Morales para que declare en el caso de trata de personas. La orden la dio la tarde de este jueves, 10 de octubre, luego de que Morales se negara a ir a Fiscal\u00eda a declarar. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Noticia en desarrollo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">#Bolivia #EvoMorales #Fiscal\u00eda #tratadepersonas <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fiscal\u00eda de Bolivia anuncia orden de aprehensi\u00f3n contra Evo Morales para que declare en el caso de trata de personas. La orden la dio la tarde de este jueves, 10 de octubre, luego de que Morales se negara a ir a Fiscal\u00eda a declarar. Noticia en desarrollo. #Bolivia #EvoMorales #Fiscal\u00eda #tratadepersonas<\/p>\n","protected":false},"author":1,"featured_media":7206,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54],"tags":[],"class_list":["post-7304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fiscal\u00eda de Bolivia emite orden de aprehensi\u00f3n contra Evo Morales<\/title>\n<meta name=\"description\" content=\"Fiscal\u00eda de Bolivia anuncia orden de aprehensi\u00f3n contra Evo Morales para que declare en el caso de trata de personas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda de Bolivia emite orden de aprehensi\u00f3n contra Evo Morales\" \/>\n<meta property=\"og:description\" content=\"Fiscal\u00eda de Bolivia anuncia orden de aprehensi\u00f3n contra Evo Morales para que declare en el caso de trata de personas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\/\" \/>\n<meta property=\"og:site_name\" content=\"92.5 FOREVER Radio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063550693491\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-10T23:03:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/10\/Ecuador-FFAA-Ejercito-Militares-Defensa-ArmadadelEcuador-ForeverInforma-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"865\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ricardo Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@925forever\" \/>\n<meta name=\"twitter:site\" content=\"@925forever\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/internacional\\\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/internacional\\\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\\\/\"},\"author\":{\"name\":\"Ricardo Rodriguez\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/person\\\/2f679dd16f889ac00df6e7b648062a01\"},\"headline\":\"Fiscal\u00eda de Bolivia anuncia orden de aprehensi\u00f3n contra Evo Morales\",\"datePublished\":\"2024-10-10T23:03:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/internacional\\\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\\\/\"},\"wordCount\":66,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/internacional\\\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Ecuador-FFAA-Ejercito-Militares-Defensa-ArmadadelEcuador-ForeverInforma-1.png\",\"articleSection\":[\"Internacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/internacional\\\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/internacional\\\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\\\/\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/internacional\\\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\\\/\",\"name\":\"Fiscal\u00eda de Bolivia emite orden de aprehensi\u00f3n contra Evo Morales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/internacional\\\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/internacional\\\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Ecuador-FFAA-Ejercito-Militares-Defensa-ArmadadelEcuador-ForeverInforma-1.png\",\"datePublished\":\"2024-10-10T23:03:33+00:00\",\"description\":\"Fiscal\u00eda de Bolivia anuncia orden de aprehensi\u00f3n contra Evo Morales para que declare en el caso de trata de personas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/internacional\\\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/internacional\\\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/internacional\\\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Ecuador-FFAA-Ejercito-Militares-Defensa-ArmadadelEcuador-ForeverInforma-1.png\",\"contentUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Ecuador-FFAA-Ejercito-Militares-Defensa-ArmadadelEcuador-ForeverInforma-1.png\",\"width\":1280,\"height\":865},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/internacional\\\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiscal\u00eda de Bolivia anuncia orden de aprehensi\u00f3n contra Evo Morales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\",\"name\":\"92.5 FOREVER Radio\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\",\"name\":\"92.5 FOREVER Radio\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-logo-forever.png\",\"contentUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-logo-forever.png\",\"width\":180,\"height\":154,\"caption\":\"92.5 FOREVER Radio\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100063550693491\",\"https:\\\/\\\/x.com\\\/925forever\",\"https:\\\/\\\/www.instagram.com\\\/radioforever925\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/person\\\/2f679dd16f889ac00df6e7b648062a01\",\"name\":\"Ricardo Rodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"caption\":\"Ricardo Rodriguez\"},\"sameAs\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\"],\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/author\\\/superdmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda de Bolivia emite orden de aprehensi\u00f3n contra Evo Morales","description":"Fiscal\u00eda de Bolivia anuncia orden de aprehensi\u00f3n contra Evo Morales para que declare en el caso de trata de personas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\/","og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda de Bolivia emite orden de aprehensi\u00f3n contra Evo Morales","og_description":"Fiscal\u00eda de Bolivia anuncia orden de aprehensi\u00f3n contra Evo Morales para que declare en el caso de trata de personas.","og_url":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\/","og_site_name":"92.5 FOREVER Radio","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063550693491","article_published_time":"2024-10-10T23:03:33+00:00","og_image":[{"width":1280,"height":865,"url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/10\/Ecuador-FFAA-Ejercito-Militares-Defensa-ArmadadelEcuador-ForeverInforma-1.png","type":"image\/png"}],"author":"Ricardo Rodriguez","twitter_card":"summary_large_image","twitter_creator":"@925forever","twitter_site":"@925forever","twitter_misc":{"Escrito por":"Ricardo Rodriguez","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\/#article","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\/"},"author":{"name":"Ricardo Rodriguez","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01"},"headline":"Fiscal\u00eda de Bolivia anuncia orden de aprehensi\u00f3n contra Evo Morales","datePublished":"2024-10-10T23:03:33+00:00","mainEntityOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\/"},"wordCount":66,"commentCount":0,"publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/10\/Ecuador-FFAA-Ejercito-Militares-Defensa-ArmadadelEcuador-ForeverInforma-1.png","articleSection":["Internacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/foreverfutbol.com.ec\/radio\/internacional\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\/","name":"Fiscal\u00eda de Bolivia emite orden de aprehensi\u00f3n contra Evo Morales","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\/#primaryimage"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/10\/Ecuador-FFAA-Ejercito-Militares-Defensa-ArmadadelEcuador-ForeverInforma-1.png","datePublished":"2024-10-10T23:03:33+00:00","description":"Fiscal\u00eda de Bolivia anuncia orden de aprehensi\u00f3n contra Evo Morales para que declare en el caso de trata de personas.","breadcrumb":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/foreverfutbol.com.ec\/radio\/internacional\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\/#primaryimage","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/10\/Ecuador-FFAA-Ejercito-Militares-Defensa-ArmadadelEcuador-ForeverInforma-1.png","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/10\/Ecuador-FFAA-Ejercito-Militares-Defensa-ArmadadelEcuador-ForeverInforma-1.png","width":1280,"height":865},{"@type":"BreadcrumbList","@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/fiscalia-de-bolivia-anuncia-orden-de-aprehension-contra-evo-morales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/foreverfutbol.com.ec\/radio\/"},{"@type":"ListItem","position":2,"name":"Fiscal\u00eda de Bolivia anuncia orden de aprehensi\u00f3n contra Evo Morales"}]},{"@type":"WebSite","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website","url":"https:\/\/foreverfutbol.com.ec\/radio\/","name":"92.5 FOREVER Radio","description":"","publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/foreverfutbol.com.ec\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization","name":"92.5 FOREVER Radio","url":"https:\/\/foreverfutbol.com.ec\/radio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","width":180,"height":154,"caption":"92.5 FOREVER Radio"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063550693491","https:\/\/x.com\/925forever","https:\/\/www.instagram.com\/radioforever925\/"]},{"@type":"Person","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01","name":"Ricardo Rodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","caption":"Ricardo Rodriguez"},"sameAs":["https:\/\/foreverfutbol.com.ec\/radio"],"url":"https:\/\/foreverfutbol.com.ec\/radio\/author\/superdmin\/"}]}},"_links":{"self":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/7304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/comments?post=7304"}],"version-history":[{"count":1,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/7304\/revisions"}],"predecessor-version":[{"id":7308,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/7304\/revisions\/7308"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media\/7206"}],"wp:attachment":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media?parent=7304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/categories?post=7304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/tags?post=7304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}