{"id":7172,"date":"2024-10-03T10:41:31","date_gmt":"2024-10-03T15:41:31","guid":{"rendered":"https:\/\/foreverfutbol.com.ec\/radio\/?p=7172"},"modified":"2024-10-03T10:41:35","modified_gmt":"2024-10-03T15:41:35","slug":"gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones","status":"publish","type":"post","link":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\/","title":{"rendered":"Gobierno declara Estado de excepci\u00f3n en 6 provincias y toque de queda en 20 cantones"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El presidente Daniel Noboa decret\u00f3 un nuevo estado de excepci\u00f3n este jueves 3 de octubre en cantones de ocho provincias por 60 d\u00edas y toque de queda en 20 localidades del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La nueva medida regir\u00e1 en las provincias de Guayas, Los R\u00edos, Manab\u00ed, Orellana, Santa Elena, El Oro; el Distrito Metropolitano de Quito de la provincia de Pichincha y, el cant\u00f3n Camilo Ponce Enr\u00edquez de la provincia de Azuay.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La capital no estaba en un estado de excepci\u00f3n por cuestiones de inseguridad desde abril del 2024, cuando culminaron los 90 d\u00edas del decreto emitido en enero del 2024, ante la declaratoria de guerra contra los grupos terroristas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Gobierno describe que Quito, al igual que las otras localidades incluidas en este documento oficial, ha sido uno de los focos de mayor intensidad de ataques criminales. Adem\u00e1s, se\u00f1ala que seg\u00fan un an\u00e1lisis policial, registra m\u00e1s asesinatos y sicariatos que entre enero y septiembre del anterior a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Este recurso constitucional implicar\u00e1 la suspensi\u00f3n de los siguientes derechos:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El derecho a la inviolabilidad de domicilio, que consistir\u00e1 en la realizaci\u00f3n de inspecciones, allanamientos, y las requisas sin \u00f3rdenes judiciales.<\/li>\n\n\n\n<li>El derecho a la inviolabilidad de correspondencia, que pretende la identificaci\u00f3n, an\u00e1lisis y recopilaci\u00f3n de mensajes que tengan por objeto el ocultamiento de cualquier miembro del grupo armado organizado.<\/li>\n\n\n\n<li>El derecho a la libertad de reuni\u00f3n, que consiste en impedir cualquier acci\u00f3n que afecte la seguridad y el orden p\u00fablico.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">La restricci\u00f3n a la libertad de tr\u00e1nsito, conocido como toque de queda, se implementar\u00e1 de 22:00 a 06:00 en 20 localidades de cuatro provincias:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Azuay: Cant\u00f3n Camilo Ponce Enr\u00edquez<\/li>\n\n\n\n<li>Guayas: Dur\u00e1n, Balao y la parroquiaTenguel<\/li>\n\n\n\n<li>Los R\u00edos: Babahoyo, Buena Fe, Quevedo, Puebloviejo, Vinces, Valencia,Ventanas Mocache, Urdaneta, Baba, Palenque, Quinsaloma y Montalvo<\/li>\n\n\n\n<li>Orellana: La Joya De Los Sachas, Puerto Francisco de Orellana y Loreto.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Este conjunto de \u00f3rdenes fueron motivados por la grave conmoci\u00f3n interna y conflicto armado interno, contemplado en el decreto ejecutivo No. 218 de 07 de abril de 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">#Estadodeexcepci\u00f3n #toquedequeda #Ecuador #DanielNoboa #FFAA #Quito #Guayaquil <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Daniel Noboa decret\u00f3 un nuevo estado de excepci\u00f3n este jueves 3 de octubre en cantones de ocho provincias por 60 d\u00edas y toque de queda en 20 localidades del pa\u00eds. La nueva medida regir\u00e1 en las provincias de Guayas, Los R\u00edos, Manab\u00ed, Orellana, Santa Elena, El Oro; el Distrito Metropolitano de Quito de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7173,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52],"tags":[],"class_list":["post-7172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estado de excepci\u00f3n y toque de queda en varias zonas en Ecuador<\/title>\n<meta name=\"description\" content=\"Daniel Noboa decret\u00f3 un nuevo estado de excepci\u00f3n este jueves 3 de octubre por 60 d\u00edas y toque de queda en 20 localidades del pa\u00eds.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estado de excepci\u00f3n y toque de queda en varias zonas en Ecuador\" \/>\n<meta property=\"og:description\" content=\"Daniel Noboa decret\u00f3 un nuevo estado de excepci\u00f3n este jueves 3 de octubre por 60 d\u00edas y toque de queda en 20 localidades del pa\u00eds.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\/\" \/>\n<meta property=\"og:site_name\" content=\"92.5 FOREVER Radio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063550693491\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-03T15:41:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-03T15:41:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/10\/17212562244085-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ricardo Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@925forever\" \/>\n<meta name=\"twitter:site\" content=\"@925forever\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\\\/\"},\"author\":{\"name\":\"Ricardo Rodriguez\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/person\\\/2f679dd16f889ac00df6e7b648062a01\"},\"headline\":\"Gobierno declara Estado de excepci\u00f3n en 6 provincias y toque de queda en 20 cantones\",\"datePublished\":\"2024-10-03T15:41:31+00:00\",\"dateModified\":\"2024-10-03T15:41:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\\\/\"},\"wordCount\":368,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/17212562244085-scaled.jpg\",\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\\\/\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\\\/\",\"name\":\"Estado de excepci\u00f3n y toque de queda en varias zonas en Ecuador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/17212562244085-scaled.jpg\",\"datePublished\":\"2024-10-03T15:41:31+00:00\",\"dateModified\":\"2024-10-03T15:41:35+00:00\",\"description\":\"Daniel Noboa decret\u00f3 un nuevo estado de excepci\u00f3n este jueves 3 de octubre por 60 d\u00edas y toque de queda en 20 localidades del pa\u00eds.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/17212562244085-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/17212562244085-scaled.jpg\",\"width\":2560,\"height\":1708},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobierno declara Estado de excepci\u00f3n en 6 provincias y toque de queda en 20 cantones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\",\"name\":\"92.5 FOREVER Radio\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\",\"name\":\"92.5 FOREVER Radio\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-logo-forever.png\",\"contentUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-logo-forever.png\",\"width\":180,\"height\":154,\"caption\":\"92.5 FOREVER Radio\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100063550693491\",\"https:\\\/\\\/x.com\\\/925forever\",\"https:\\\/\\\/www.instagram.com\\\/radioforever925\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/person\\\/2f679dd16f889ac00df6e7b648062a01\",\"name\":\"Ricardo Rodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"caption\":\"Ricardo Rodriguez\"},\"sameAs\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\"],\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/author\\\/superdmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estado de excepci\u00f3n y toque de queda en varias zonas en Ecuador","description":"Daniel Noboa decret\u00f3 un nuevo estado de excepci\u00f3n este jueves 3 de octubre por 60 d\u00edas y toque de queda en 20 localidades del pa\u00eds.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\/","og_locale":"es_ES","og_type":"article","og_title":"Estado de excepci\u00f3n y toque de queda en varias zonas en Ecuador","og_description":"Daniel Noboa decret\u00f3 un nuevo estado de excepci\u00f3n este jueves 3 de octubre por 60 d\u00edas y toque de queda en 20 localidades del pa\u00eds.","og_url":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\/","og_site_name":"92.5 FOREVER Radio","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063550693491","article_published_time":"2024-10-03T15:41:31+00:00","article_modified_time":"2024-10-03T15:41:35+00:00","og_image":[{"width":2560,"height":1708,"url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/10\/17212562244085-scaled.jpg","type":"image\/jpeg"}],"author":"Ricardo Rodriguez","twitter_card":"summary_large_image","twitter_creator":"@925forever","twitter_site":"@925forever","twitter_misc":{"Escrito por":"Ricardo Rodriguez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\/#article","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\/"},"author":{"name":"Ricardo Rodriguez","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01"},"headline":"Gobierno declara Estado de excepci\u00f3n en 6 provincias y toque de queda en 20 cantones","datePublished":"2024-10-03T15:41:31+00:00","dateModified":"2024-10-03T15:41:35+00:00","mainEntityOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\/"},"wordCount":368,"commentCount":0,"publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/10\/17212562244085-scaled.jpg","articleSection":["Pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\/","name":"Estado de excepci\u00f3n y toque de queda en varias zonas en Ecuador","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\/#primaryimage"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/10\/17212562244085-scaled.jpg","datePublished":"2024-10-03T15:41:31+00:00","dateModified":"2024-10-03T15:41:35+00:00","description":"Daniel Noboa decret\u00f3 un nuevo estado de excepci\u00f3n este jueves 3 de octubre por 60 d\u00edas y toque de queda en 20 localidades del pa\u00eds.","breadcrumb":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\/#primaryimage","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/10\/17212562244085-scaled.jpg","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/10\/17212562244085-scaled.jpg","width":2560,"height":1708},{"@type":"BreadcrumbList","@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-declara-estado-de-excepcion-en-6-provincias-y-toque-de-queda-en-20-cantones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/foreverfutbol.com.ec\/radio\/"},{"@type":"ListItem","position":2,"name":"Gobierno declara Estado de excepci\u00f3n en 6 provincias y toque de queda en 20 cantones"}]},{"@type":"WebSite","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website","url":"https:\/\/foreverfutbol.com.ec\/radio\/","name":"92.5 FOREVER Radio","description":"","publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/foreverfutbol.com.ec\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization","name":"92.5 FOREVER Radio","url":"https:\/\/foreverfutbol.com.ec\/radio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","width":180,"height":154,"caption":"92.5 FOREVER Radio"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063550693491","https:\/\/x.com\/925forever","https:\/\/www.instagram.com\/radioforever925\/"]},{"@type":"Person","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01","name":"Ricardo Rodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","caption":"Ricardo Rodriguez"},"sameAs":["https:\/\/foreverfutbol.com.ec\/radio"],"url":"https:\/\/foreverfutbol.com.ec\/radio\/author\/superdmin\/"}]}},"_links":{"self":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/7172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/comments?post=7172"}],"version-history":[{"count":1,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/7172\/revisions"}],"predecessor-version":[{"id":7174,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/7172\/revisions\/7174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media\/7173"}],"wp:attachment":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media?parent=7172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/categories?post=7172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/tags?post=7172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}