{"id":7146,"date":"2024-10-01T15:49:02","date_gmt":"2024-10-01T20:49:02","guid":{"rendered":"https:\/\/foreverfutbol.com.ec\/radio\/?p=7146"},"modified":"2024-10-02T10:41:02","modified_gmt":"2024-10-02T15:41:02","slug":"el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos","status":"publish","type":"post","link":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\/","title":{"rendered":"El excontralor Carlos P\u00f3lit es sentenciado a 10 a\u00f1os de prisi\u00f3n por lavado de activos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El excontralor general de Ecuador, Carlos P\u00f3lit, ha sido sentenciado a 10 a\u00f1os de prisi\u00f3n por la jueza Kathleen Williams en una corte federal de Miami. Esta condena se dicta en el marco de su participaci\u00f3n en un esquema de lavado de dinero y corrupci\u00f3n vinculado a la constructora brasile\u00f1a Odebrecht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de la pena carcelaria, P\u00f3lit enfrentar\u00e1 la confiscaci\u00f3n de bienes por valor de 16.5 millones de d\u00f3lares, los cuales fueron adquiridos con fondos provenientes de sobornos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el proceso judicial, P\u00f3lit fue encontrado culpable de seis cargos, que incluyen conspiraci\u00f3n para cometer lavado de dinero y la realizaci\u00f3n de transacciones con propiedades derivadas de actividades il\u00edcitas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras la defensa de P\u00f3lit argumentaba por una sentencia de no m\u00e1s de seis a\u00f1os, la Fiscal\u00eda estadounidense logr\u00f3 convencer al tribunal de imponer una pena de casi dos d\u00e9cadas, reflejando la gravedad de los delitos de corrupci\u00f3n y lavado de activos cometidos durante su tiempo en el cargo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este caso es parte de las repercusiones legales m\u00e1s amplias del esc\u00e1ndalo de Odebrecht, que ha afectado a m\u00faltiples figuras pol\u00edticas en Am\u00e9rica Latina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">#CarlosP\u00f3lit #contralor #lavadodeactivos #Miami #p\u00f3lit #Ecuador <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El excontralor general de Ecuador, Carlos P\u00f3lit, ha sido sentenciado a 10 a\u00f1os de prisi\u00f3n por la jueza Kathleen Williams en una corte federal de Miami. Esta condena se dicta en el marco de su participaci\u00f3n en un esquema de lavado de dinero y corrupci\u00f3n vinculado a la constructora brasile\u00f1a Odebrecht. Adem\u00e1s de la pena [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7150,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52],"tags":[],"class_list":["post-7146","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carlos P\u00f3lit, sentenciado a 19 a\u00f1os por lavado de activos<\/title>\n<meta name=\"description\" content=\"Adem\u00e1s de la pena carcelaria, P\u00f3lit enfrentar\u00e1 la confiscaci\u00f3n de bienes por valor de 16.5 millones de d\u00f3lares...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carlos P\u00f3lit, sentenciado a 19 a\u00f1os por lavado de activos\" \/>\n<meta property=\"og:description\" content=\"Adem\u00e1s de la pena carcelaria, P\u00f3lit enfrentar\u00e1 la confiscaci\u00f3n de bienes por valor de 16.5 millones de d\u00f3lares...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\/\" \/>\n<meta property=\"og:site_name\" content=\"92.5 FOREVER Radio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063550693491\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-01T20:49:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-02T15:41:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/10\/CarlosPolit-contralor-lavadodeactivos-Miami-polit-Ecuador-ForeverInforma-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"865\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ricardo Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@925forever\" \/>\n<meta name=\"twitter:site\" content=\"@925forever\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\\\/\"},\"author\":{\"name\":\"Ricardo Rodriguez\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/person\\\/2f679dd16f889ac00df6e7b648062a01\"},\"headline\":\"El excontralor Carlos P\u00f3lit es sentenciado a 10 a\u00f1os de prisi\u00f3n por lavado de activos\",\"datePublished\":\"2024-10-01T20:49:02+00:00\",\"dateModified\":\"2024-10-02T15:41:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\\\/\"},\"wordCount\":229,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/CarlosPolit-contralor-lavadodeactivos-Miami-polit-Ecuador-ForeverInforma-.png\",\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\\\/\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\\\/\",\"name\":\"Carlos P\u00f3lit, sentenciado a 19 a\u00f1os por lavado de activos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/CarlosPolit-contralor-lavadodeactivos-Miami-polit-Ecuador-ForeverInforma-.png\",\"datePublished\":\"2024-10-01T20:49:02+00:00\",\"dateModified\":\"2024-10-02T15:41:02+00:00\",\"description\":\"Adem\u00e1s de la pena carcelaria, P\u00f3lit enfrentar\u00e1 la confiscaci\u00f3n de bienes por valor de 16.5 millones de d\u00f3lares...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/CarlosPolit-contralor-lavadodeactivos-Miami-polit-Ecuador-ForeverInforma-.png\",\"contentUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/CarlosPolit-contralor-lavadodeactivos-Miami-polit-Ecuador-ForeverInforma-.png\",\"width\":1280,\"height\":865},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El excontralor Carlos P\u00f3lit es sentenciado a 10 a\u00f1os de prisi\u00f3n por lavado de activos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\",\"name\":\"92.5 FOREVER Radio\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\",\"name\":\"92.5 FOREVER Radio\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-logo-forever.png\",\"contentUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-logo-forever.png\",\"width\":180,\"height\":154,\"caption\":\"92.5 FOREVER Radio\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100063550693491\",\"https:\\\/\\\/x.com\\\/925forever\",\"https:\\\/\\\/www.instagram.com\\\/radioforever925\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/person\\\/2f679dd16f889ac00df6e7b648062a01\",\"name\":\"Ricardo Rodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"caption\":\"Ricardo Rodriguez\"},\"sameAs\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\"],\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/author\\\/superdmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carlos P\u00f3lit, sentenciado a 19 a\u00f1os por lavado de activos","description":"Adem\u00e1s de la pena carcelaria, P\u00f3lit enfrentar\u00e1 la confiscaci\u00f3n de bienes por valor de 16.5 millones de d\u00f3lares...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\/","og_locale":"es_ES","og_type":"article","og_title":"Carlos P\u00f3lit, sentenciado a 19 a\u00f1os por lavado de activos","og_description":"Adem\u00e1s de la pena carcelaria, P\u00f3lit enfrentar\u00e1 la confiscaci\u00f3n de bienes por valor de 16.5 millones de d\u00f3lares...","og_url":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\/","og_site_name":"92.5 FOREVER Radio","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063550693491","article_published_time":"2024-10-01T20:49:02+00:00","article_modified_time":"2024-10-02T15:41:02+00:00","og_image":[{"width":1280,"height":865,"url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/10\/CarlosPolit-contralor-lavadodeactivos-Miami-polit-Ecuador-ForeverInforma-.png","type":"image\/png"}],"author":"Ricardo Rodriguez","twitter_card":"summary_large_image","twitter_creator":"@925forever","twitter_site":"@925forever","twitter_misc":{"Escrito por":"Ricardo Rodriguez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\/#article","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\/"},"author":{"name":"Ricardo Rodriguez","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01"},"headline":"El excontralor Carlos P\u00f3lit es sentenciado a 10 a\u00f1os de prisi\u00f3n por lavado de activos","datePublished":"2024-10-01T20:49:02+00:00","dateModified":"2024-10-02T15:41:02+00:00","mainEntityOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\/"},"wordCount":229,"commentCount":0,"publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/10\/CarlosPolit-contralor-lavadodeactivos-Miami-polit-Ecuador-ForeverInforma-.png","articleSection":["Pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/foreverfutbol.com.ec\/radio\/politica\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\/","name":"Carlos P\u00f3lit, sentenciado a 19 a\u00f1os por lavado de activos","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\/#primaryimage"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/10\/CarlosPolit-contralor-lavadodeactivos-Miami-polit-Ecuador-ForeverInforma-.png","datePublished":"2024-10-01T20:49:02+00:00","dateModified":"2024-10-02T15:41:02+00:00","description":"Adem\u00e1s de la pena carcelaria, P\u00f3lit enfrentar\u00e1 la confiscaci\u00f3n de bienes por valor de 16.5 millones de d\u00f3lares...","breadcrumb":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/foreverfutbol.com.ec\/radio\/politica\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\/#primaryimage","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/10\/CarlosPolit-contralor-lavadodeactivos-Miami-polit-Ecuador-ForeverInforma-.png","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/10\/CarlosPolit-contralor-lavadodeactivos-Miami-polit-Ecuador-ForeverInforma-.png","width":1280,"height":865},{"@type":"BreadcrumbList","@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/el-excontralor-carlos-polit-es-sentenciado-a-19-anos-de-prision-por-lavado-de-activos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/foreverfutbol.com.ec\/radio\/"},{"@type":"ListItem","position":2,"name":"El excontralor Carlos P\u00f3lit es sentenciado a 10 a\u00f1os de prisi\u00f3n por lavado de activos"}]},{"@type":"WebSite","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website","url":"https:\/\/foreverfutbol.com.ec\/radio\/","name":"92.5 FOREVER Radio","description":"","publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/foreverfutbol.com.ec\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization","name":"92.5 FOREVER Radio","url":"https:\/\/foreverfutbol.com.ec\/radio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","width":180,"height":154,"caption":"92.5 FOREVER Radio"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063550693491","https:\/\/x.com\/925forever","https:\/\/www.instagram.com\/radioforever925\/"]},{"@type":"Person","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01","name":"Ricardo Rodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","caption":"Ricardo Rodriguez"},"sameAs":["https:\/\/foreverfutbol.com.ec\/radio"],"url":"https:\/\/foreverfutbol.com.ec\/radio\/author\/superdmin\/"}]}},"_links":{"self":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/7146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/comments?post=7146"}],"version-history":[{"count":2,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/7146\/revisions"}],"predecessor-version":[{"id":7159,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/7146\/revisions\/7159"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media\/7150"}],"wp:attachment":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media?parent=7146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/categories?post=7146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/tags?post=7146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}