{"id":6878,"date":"2024-09-17T12:23:28","date_gmt":"2024-09-17T17:23:28","guid":{"rendered":"https:\/\/foreverfutbol.com.ec\/radio\/?p=6878"},"modified":"2024-09-17T12:54:53","modified_gmt":"2024-09-17T17:54:53","slug":"gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais","status":"publish","type":"post","link":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/","title":{"rendered":"Gobierno de Ecuador anuncia apagones de 8 horas por 4 d\u00edas en todo el pa\u00eds"},"content":{"rendered":"\n<p>El Gobierno Nacional anunci\u00f3 que habr\u00e1 apagones de ocho horas en todo el territorio ecuatoriano desde el lunes 23 de septiembre hasta el jueves 26 de septiembre, desde las 22:00 hasta las 06:00 del d\u00eda siguiente, por la crisis de generaci\u00f3n el\u00e9ctrica.<\/p>\n\n\n\n<p>Este anuncio se produjo casi a la medianoche de este martes 17 de septiembre, y un d\u00eda despu\u00e9s que se comunicara que el mi\u00e9rcoles 18 de septiembre habr\u00e1 un corte nocturno prolongado de ocho horas (de 22:00 a 06:00) para realizar un mantenimiento preventivo en todas las instalaciones del Sistema Nacional de Transmisi\u00f3n.<\/p>\n\n\n\n<p>La decisi\u00f3n de anunciar los racionamientos energ\u00e9ticos por cuatro d\u00edas de la siguiente semana se tom\u00f3 bajo la justificaci\u00f3n de vivir el peor estiaje de los \u00faltimos 61 a\u00f1os, y para \u00abmanejar de forma responsable\u00bb el control del sistema el\u00e9ctrico.<\/p>\n\n\n\n<p>Por esta medida, se implementar\u00e1 la modalidad de teletrabajo en el sector p\u00fablico los d\u00edas jueves, viernes de esta y la pr\u00f3xima semana. <\/p>\n\n\n\n<p>La Secretar\u00eda de Comunicaci\u00f3n de la Presidencia asever\u00f3 que el horario de corte establecido ha sido escogido con la finalidad de generar el menor impacto posible en las actividades productivas y el desarrollo de jornadas laborales.<\/p>\n\n\n\n<p>Apuntaron que han desplegado una serie de acciones para enfrentar esta crisis y reducir su impacto, como la puesta en marcha del barco generador, generadores permanentes de tierra, aprobaci\u00f3n de reglamentos para importaci\u00f3n de gas natural, complementaci\u00f3n de infraestructura energ\u00e9tica que estuvo abandonada y normativas que permiten generaci\u00f3n del sector privado.<\/p>\n\n\n\n<p>Indicaron que comunicar\u00e1n oportunamente la situaci\u00f3n energ\u00e9tica que tomar\u00e1n en el futuro.<\/p>\n\n\n\n<p>La ministra M\u00f3nica Palencia anunci\u00f3 que se decretar\u00eda toque de queda por el apag\u00f3n del mi\u00e9rcoles 18 de septiembre, sin embargo, el Decreto Ejecutivo que ordenar\u00eda esa medida a\u00fan no se ha emitido. Tras conocerse esta nueva serie de cortes de luz prolongados, se estima que ese recurso tambi\u00e9n estar\u00e1 vigente la siguiente semana.<\/p>\n\n\n\n<p>#apag\u00f3n #apagones #Ecuador #DanielNoboa #crisisel\u00e9ctrica <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno Nacional anunci\u00f3 que habr\u00e1 apagones de ocho horas en todo el territorio ecuatoriano desde el lunes 23 de septiembre hasta el jueves 26 de septiembre, desde las 22:00 hasta las 06:00 del d\u00eda siguiente, por la crisis de generaci\u00f3n el\u00e9ctrica. Este anuncio se produjo casi a la medianoche de este martes 17 de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6886,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52],"tags":[],"class_list":["post-6878","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gobierno de Ecuador anuncia apagones de 8 horas por 4 d\u00edas<\/title>\n<meta name=\"description\" content=\"El Gobierno anunci\u00f3 que habr\u00e1 apagones de ocho horas en todo el territorio ecuatoriano desde el lunes 23 hasta el jueves 26 de septiembre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobierno de Ecuador anuncia apagones de 8 horas por 4 d\u00edas\" \/>\n<meta property=\"og:description\" content=\"El Gobierno anunci\u00f3 que habr\u00e1 apagones de ocho horas en todo el territorio ecuatoriano desde el lunes 23 hasta el jueves 26 de septiembre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/\" \/>\n<meta property=\"og:site_name\" content=\"92.5 FOREVER Radio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063550693491\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-17T17:23:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-17T17:54:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/09\/apagon-apagones-Ecuador-DanielNoboa-crisiselectrica-ForeverInforma-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"865\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ricardo Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@925forever\" \/>\n<meta name=\"twitter:site\" content=\"@925forever\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/\"},\"author\":{\"name\":\"Ricardo Rodriguez\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01\"},\"headline\":\"Gobierno de Ecuador anuncia apagones de 8 horas por 4 d\u00edas en todo el pa\u00eds\",\"datePublished\":\"2024-09-17T17:23:28+00:00\",\"dateModified\":\"2024-09-17T17:54:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/\"},\"wordCount\":357,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#organization\"},\"image\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/09\/apagon-apagones-Ecuador-DanielNoboa-crisiselectrica-ForeverInforma-.png\",\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/\",\"url\":\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/\",\"name\":\"Gobierno de Ecuador anuncia apagones de 8 horas por 4 d\u00edas\",\"isPartOf\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/09\/apagon-apagones-Ecuador-DanielNoboa-crisiselectrica-ForeverInforma-.png\",\"datePublished\":\"2024-09-17T17:23:28+00:00\",\"dateModified\":\"2024-09-17T17:54:53+00:00\",\"description\":\"El Gobierno anunci\u00f3 que habr\u00e1 apagones de ocho horas en todo el territorio ecuatoriano desde el lunes 23 hasta el jueves 26 de septiembre.\",\"breadcrumb\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/#primaryimage\",\"url\":\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/09\/apagon-apagones-Ecuador-DanielNoboa-crisiselectrica-ForeverInforma-.png\",\"contentUrl\":\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/09\/apagon-apagones-Ecuador-DanielNoboa-crisiselectrica-ForeverInforma-.png\",\"width\":1280,\"height\":865},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/foreverfutbol.com.ec\/radio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobierno de Ecuador anuncia apagones de 8 horas por 4 d\u00edas en todo el pa\u00eds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#website\",\"url\":\"https:\/\/foreverfutbol.com.ec\/radio\/\",\"name\":\"92.5 FOREVER Radio\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/foreverfutbol.com.ec\/radio\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#organization\",\"name\":\"92.5 FOREVER Radio\",\"url\":\"https:\/\/foreverfutbol.com.ec\/radio\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png\",\"contentUrl\":\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png\",\"width\":180,\"height\":154,\"caption\":\"92.5 FOREVER Radio\"},\"image\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100063550693491\",\"https:\/\/x.com\/925forever\",\"https:\/\/www.instagram.com\/radioforever925\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01\",\"name\":\"Ricardo Rodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/e40e2129642cc37300c493eac481301df5ff08b78ad01765fa6145185e95fb7e?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e40e2129642cc37300c493eac481301df5ff08b78ad01765fa6145185e95fb7e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e40e2129642cc37300c493eac481301df5ff08b78ad01765fa6145185e95fb7e?s=96&d=mm&r=g\",\"caption\":\"Ricardo Rodriguez\"},\"sameAs\":[\"https:\/\/foreverfutbol.com.ec\/radio\"],\"url\":\"https:\/\/foreverfutbol.com.ec\/radio\/author\/superdmin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gobierno de Ecuador anuncia apagones de 8 horas por 4 d\u00edas","description":"El Gobierno anunci\u00f3 que habr\u00e1 apagones de ocho horas en todo el territorio ecuatoriano desde el lunes 23 hasta el jueves 26 de septiembre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/","og_locale":"es_ES","og_type":"article","og_title":"Gobierno de Ecuador anuncia apagones de 8 horas por 4 d\u00edas","og_description":"El Gobierno anunci\u00f3 que habr\u00e1 apagones de ocho horas en todo el territorio ecuatoriano desde el lunes 23 hasta el jueves 26 de septiembre.","og_url":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/","og_site_name":"92.5 FOREVER Radio","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063550693491","article_published_time":"2024-09-17T17:23:28+00:00","article_modified_time":"2024-09-17T17:54:53+00:00","og_image":[{"width":1280,"height":865,"url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/09\/apagon-apagones-Ecuador-DanielNoboa-crisiselectrica-ForeverInforma-.png","type":"image\/png"}],"author":"Ricardo Rodriguez","twitter_card":"summary_large_image","twitter_creator":"@925forever","twitter_site":"@925forever","twitter_misc":{"Escrito por":"Ricardo Rodriguez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/#article","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/"},"author":{"name":"Ricardo Rodriguez","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01"},"headline":"Gobierno de Ecuador anuncia apagones de 8 horas por 4 d\u00edas en todo el pa\u00eds","datePublished":"2024-09-17T17:23:28+00:00","dateModified":"2024-09-17T17:54:53+00:00","mainEntityOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/"},"wordCount":357,"commentCount":0,"publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/09\/apagon-apagones-Ecuador-DanielNoboa-crisiselectrica-ForeverInforma-.png","articleSection":["Pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/","name":"Gobierno de Ecuador anuncia apagones de 8 horas por 4 d\u00edas","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/#primaryimage"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/09\/apagon-apagones-Ecuador-DanielNoboa-crisiselectrica-ForeverInforma-.png","datePublished":"2024-09-17T17:23:28+00:00","dateModified":"2024-09-17T17:54:53+00:00","description":"El Gobierno anunci\u00f3 que habr\u00e1 apagones de ocho horas en todo el territorio ecuatoriano desde el lunes 23 hasta el jueves 26 de septiembre.","breadcrumb":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/#primaryimage","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/09\/apagon-apagones-Ecuador-DanielNoboa-crisiselectrica-ForeverInforma-.png","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/09\/apagon-apagones-Ecuador-DanielNoboa-crisiselectrica-ForeverInforma-.png","width":1280,"height":865},{"@type":"BreadcrumbList","@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/gobierno-de-ecuador-anuncia-apagones-de-8-horas-por-4-dias-en-todo-el-pais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/foreverfutbol.com.ec\/radio\/"},{"@type":"ListItem","position":2,"name":"Gobierno de Ecuador anuncia apagones de 8 horas por 4 d\u00edas en todo el pa\u00eds"}]},{"@type":"WebSite","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website","url":"https:\/\/foreverfutbol.com.ec\/radio\/","name":"92.5 FOREVER Radio","description":"","publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/foreverfutbol.com.ec\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization","name":"92.5 FOREVER Radio","url":"https:\/\/foreverfutbol.com.ec\/radio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","width":180,"height":154,"caption":"92.5 FOREVER Radio"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063550693491","https:\/\/x.com\/925forever","https:\/\/www.instagram.com\/radioforever925\/"]},{"@type":"Person","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01","name":"Ricardo Rodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e40e2129642cc37300c493eac481301df5ff08b78ad01765fa6145185e95fb7e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e40e2129642cc37300c493eac481301df5ff08b78ad01765fa6145185e95fb7e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e40e2129642cc37300c493eac481301df5ff08b78ad01765fa6145185e95fb7e?s=96&d=mm&r=g","caption":"Ricardo Rodriguez"},"sameAs":["https:\/\/foreverfutbol.com.ec\/radio"],"url":"https:\/\/foreverfutbol.com.ec\/radio\/author\/superdmin\/"}]}},"_links":{"self":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/6878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/comments?post=6878"}],"version-history":[{"count":1,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/6878\/revisions"}],"predecessor-version":[{"id":6879,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/6878\/revisions\/6879"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media\/6886"}],"wp:attachment":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media?parent=6878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/categories?post=6878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/tags?post=6878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}