{"id":6808,"date":"2024-09-12T17:05:39","date_gmt":"2024-09-12T22:05:39","guid":{"rendered":"https:\/\/foreverfutbol.com.ec\/radio\/?p=6808"},"modified":"2024-09-12T17:05:40","modified_gmt":"2024-09-12T22:05:40","slug":"duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos","status":"publish","type":"post","link":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\/","title":{"rendered":"Duro golpe de la Polic\u00eda a dos grupos delictivos: Operativo Cero Impunidad 10 deja 55 detenidos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Polic\u00eda Nacional del Ecuador, a trav\u00e9s de la Fuerza de Investigaci\u00f3n Anticriminal (FIAC), en coordinaci\u00f3n con Fiscal\u00eda General del Estado, durante el 9 al 12 de septiembre, llev\u00f3 a cabo la operaci\u00f3n \u201cCero Impunidad 10\u201d, en las provincias de El Oro, Esmeraldas, Guayas, Manab\u00ed, Los R\u00edos, Santa Elena y Zona 8 (DMG), que permiti\u00f3 la captura de 55 ciudadanos (50 aprehendidos en flagrancia y 5 con boleta de detenci\u00f3n), quienes estar\u00edan involucrados en el cometimiento de delitos como robo de veh\u00edculos, tr\u00e1fico de drogas, armas de fuego y sicariato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este sentido, de los 50 aprehendidos: 30 personas fueron por tr\u00e1fico de drogas, 9 por tr\u00e1fico de armas y 11 por robo de veh\u00edculos. Asimismo, con esta operaci\u00f3n se afect\u00f3 a dos grupos armados organizados (GAO): dos pertenecientes al GAO \u201cChoneros\u201d y dos a \u201cLos Lobos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De manera que, en esta semana se ejecutaron 61 intervenciones, en donde se obtuvieron los siguientes indicios:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>20 armas de fuego (7 pistolas, 3 rev\u00f3lveres, 8 escopetas, 2 cartucheras)<\/li>\n\n\n\n<li>210 cartuchos<\/li>\n\n\n\n<li>58 kg de droga (127.28 kg de coca\u00edna, 0.14 kilos de hero\u00edna, 1.16 kg de marihuana)<\/li>\n\n\n\n<li>3 veh\u00edculos aprehendidos<\/li>\n\n\n\n<li>4 veh\u00edculos recuperados<\/li>\n\n\n\n<li>12 motocicletas recuperadas<\/li>\n\n\n\n<li>9 motocicletas aprehendidas<\/li>\n\n\n\n<li>29 tel\u00e9fonos celulares aprehendidos<\/li>\n\n\n\n<li>029 d\u00f3lares en efectivo<\/li>\n\n\n\n<li>24 tacos de dinamita<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Con estas acciones, la Instituci\u00f3n policial ratifica su trabajo en la lucha contra el crimen organizado y a la vez solicita a la ciudadan\u00eda continuar denunciando estos hechos delictivos llamando al 1800 335 486 (DELITO) opci\u00f3n 1, a fin de aportar con informaci\u00f3n relevante que ayude a capturar a estos antisociales y juntos trabajar por la seguridad del Ecuador. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">#OperativoCeroImpunidad #Guayas #Manab\u00ed #LosR\u00edos #50detenidos <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Polic\u00eda Nacional del Ecuador, a trav\u00e9s de la Fuerza de Investigaci\u00f3n Anticriminal (FIAC), en coordinaci\u00f3n con Fiscal\u00eda General del Estado, durante el 9 al 12 de septiembre, llev\u00f3 a cabo la operaci\u00f3n \u201cCero Impunidad 10\u201d, en las provincias de El Oro, Esmeraldas, Guayas, Manab\u00ed, Los R\u00edos, Santa Elena y Zona 8 (DMG), que permiti\u00f3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6809,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51],"tags":[],"class_list":["post-6808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sucesos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Operativo Cero Impunidad 10 deja 55 detenidos en el pa\u00eds<\/title>\n<meta name=\"description\" content=\"Con esta operaci\u00f3n se afect\u00f3 a dos grupos armados organizados (GAO): dos pertenecientes al GAO \u201cChoneros\u201d y dos a \u201cLos Lobos\u201d.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Operativo Cero Impunidad 10 deja 55 detenidos en el pa\u00eds\" \/>\n<meta property=\"og:description\" content=\"Con esta operaci\u00f3n se afect\u00f3 a dos grupos armados organizados (GAO): dos pertenecientes al GAO \u201cChoneros\u201d y dos a \u201cLos Lobos\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\/\" \/>\n<meta property=\"og:site_name\" content=\"92.5 FOREVER Radio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063550693491\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-12T22:05:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-12T22:05:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/09\/OperativoCeroImpunidad-Guayas-Manabi-LosRios-50detenidos-ForeverInforma-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"865\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ricardo Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@925forever\" \/>\n<meta name=\"twitter:site\" content=\"@925forever\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/sucesos\\\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/sucesos\\\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\\\/\"},\"author\":{\"name\":\"Ricardo Rodriguez\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/person\\\/2f679dd16f889ac00df6e7b648062a01\"},\"headline\":\"Duro golpe de la Polic\u00eda a dos grupos delictivos: Operativo Cero Impunidad 10 deja 55 detenidos\",\"datePublished\":\"2024-09-12T22:05:39+00:00\",\"dateModified\":\"2024-09-12T22:05:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/sucesos\\\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\\\/\"},\"wordCount\":281,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/sucesos\\\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/OperativoCeroImpunidad-Guayas-Manabi-LosRios-50detenidos-ForeverInforma-.png\",\"articleSection\":[\"Sucesos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/sucesos\\\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/sucesos\\\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\\\/\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/sucesos\\\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\\\/\",\"name\":\"Operativo Cero Impunidad 10 deja 55 detenidos en el pa\u00eds\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/sucesos\\\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/sucesos\\\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/OperativoCeroImpunidad-Guayas-Manabi-LosRios-50detenidos-ForeverInforma-.png\",\"datePublished\":\"2024-09-12T22:05:39+00:00\",\"dateModified\":\"2024-09-12T22:05:40+00:00\",\"description\":\"Con esta operaci\u00f3n se afect\u00f3 a dos grupos armados organizados (GAO): dos pertenecientes al GAO \u201cChoneros\u201d y dos a \u201cLos Lobos\u201d.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/sucesos\\\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/sucesos\\\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/sucesos\\\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/OperativoCeroImpunidad-Guayas-Manabi-LosRios-50detenidos-ForeverInforma-.png\",\"contentUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/OperativoCeroImpunidad-Guayas-Manabi-LosRios-50detenidos-ForeverInforma-.png\",\"width\":1280,\"height\":865},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/sucesos\\\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Duro golpe de la Polic\u00eda a dos grupos delictivos: Operativo Cero Impunidad 10 deja 55 detenidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\",\"name\":\"92.5 FOREVER Radio\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\",\"name\":\"92.5 FOREVER Radio\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-logo-forever.png\",\"contentUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-logo-forever.png\",\"width\":180,\"height\":154,\"caption\":\"92.5 FOREVER Radio\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100063550693491\",\"https:\\\/\\\/x.com\\\/925forever\",\"https:\\\/\\\/www.instagram.com\\\/radioforever925\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/person\\\/2f679dd16f889ac00df6e7b648062a01\",\"name\":\"Ricardo Rodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"caption\":\"Ricardo Rodriguez\"},\"sameAs\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\"],\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/author\\\/superdmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Operativo Cero Impunidad 10 deja 55 detenidos en el pa\u00eds","description":"Con esta operaci\u00f3n se afect\u00f3 a dos grupos armados organizados (GAO): dos pertenecientes al GAO \u201cChoneros\u201d y dos a \u201cLos Lobos\u201d.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\/","og_locale":"es_ES","og_type":"article","og_title":"Operativo Cero Impunidad 10 deja 55 detenidos en el pa\u00eds","og_description":"Con esta operaci\u00f3n se afect\u00f3 a dos grupos armados organizados (GAO): dos pertenecientes al GAO \u201cChoneros\u201d y dos a \u201cLos Lobos\u201d.","og_url":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\/","og_site_name":"92.5 FOREVER Radio","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063550693491","article_published_time":"2024-09-12T22:05:39+00:00","article_modified_time":"2024-09-12T22:05:40+00:00","og_image":[{"width":1280,"height":865,"url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/09\/OperativoCeroImpunidad-Guayas-Manabi-LosRios-50detenidos-ForeverInforma-.png","type":"image\/png"}],"author":"Ricardo Rodriguez","twitter_card":"summary_large_image","twitter_creator":"@925forever","twitter_site":"@925forever","twitter_misc":{"Escrito por":"Ricardo Rodriguez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\/#article","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\/"},"author":{"name":"Ricardo Rodriguez","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01"},"headline":"Duro golpe de la Polic\u00eda a dos grupos delictivos: Operativo Cero Impunidad 10 deja 55 detenidos","datePublished":"2024-09-12T22:05:39+00:00","dateModified":"2024-09-12T22:05:40+00:00","mainEntityOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\/"},"wordCount":281,"commentCount":0,"publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/09\/OperativoCeroImpunidad-Guayas-Manabi-LosRios-50detenidos-ForeverInforma-.png","articleSection":["Sucesos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\/","name":"Operativo Cero Impunidad 10 deja 55 detenidos en el pa\u00eds","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\/#primaryimage"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/09\/OperativoCeroImpunidad-Guayas-Manabi-LosRios-50detenidos-ForeverInforma-.png","datePublished":"2024-09-12T22:05:39+00:00","dateModified":"2024-09-12T22:05:40+00:00","description":"Con esta operaci\u00f3n se afect\u00f3 a dos grupos armados organizados (GAO): dos pertenecientes al GAO \u201cChoneros\u201d y dos a \u201cLos Lobos\u201d.","breadcrumb":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\/#primaryimage","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/09\/OperativoCeroImpunidad-Guayas-Manabi-LosRios-50detenidos-ForeverInforma-.png","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/09\/OperativoCeroImpunidad-Guayas-Manabi-LosRios-50detenidos-ForeverInforma-.png","width":1280,"height":865},{"@type":"BreadcrumbList","@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/duro-golpe-de-la-policia-a-dos-grupos-delictivos-operativo-cero-impunidad-10-deja-55-detenidos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/foreverfutbol.com.ec\/radio\/"},{"@type":"ListItem","position":2,"name":"Duro golpe de la Polic\u00eda a dos grupos delictivos: Operativo Cero Impunidad 10 deja 55 detenidos"}]},{"@type":"WebSite","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website","url":"https:\/\/foreverfutbol.com.ec\/radio\/","name":"92.5 FOREVER Radio","description":"","publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/foreverfutbol.com.ec\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization","name":"92.5 FOREVER Radio","url":"https:\/\/foreverfutbol.com.ec\/radio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","width":180,"height":154,"caption":"92.5 FOREVER Radio"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063550693491","https:\/\/x.com\/925forever","https:\/\/www.instagram.com\/radioforever925\/"]},{"@type":"Person","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01","name":"Ricardo Rodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","caption":"Ricardo Rodriguez"},"sameAs":["https:\/\/foreverfutbol.com.ec\/radio"],"url":"https:\/\/foreverfutbol.com.ec\/radio\/author\/superdmin\/"}]}},"_links":{"self":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/6808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/comments?post=6808"}],"version-history":[{"count":1,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/6808\/revisions"}],"predecessor-version":[{"id":6810,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/6808\/revisions\/6810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media\/6809"}],"wp:attachment":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media?parent=6808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/categories?post=6808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/tags?post=6808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}