{"id":6775,"date":"2024-09-10T13:18:40","date_gmt":"2024-09-10T18:18:40","guid":{"rendered":"https:\/\/foreverfutbol.com.ec\/radio\/?p=6775"},"modified":"2024-09-10T13:18:41","modified_gmt":"2024-09-10T18:18:41","slug":"comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar","status":"publish","type":"post","link":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\/","title":{"rendered":"Comisi\u00f3n de Fiscalizaci\u00f3n de la Asamblea archiv\u00f3 el juicio pol\u00edtico contra la fiscal general Diana Salazar"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Con 5 votos, la Comisi\u00f3n de Fiscalizaci\u00f3n de la Asamblea Nacional no calific\u00f3 el juicio pol\u00edtico a la fiscal general del Estado, Diana Salazar, cerca de la medianoche de este este lunes 9 de septiembre del 2024. Adem\u00e1s, retom\u00f3 los juicios pol\u00edticos contra tres exministros del r\u00e9gimen de Guillermo Lasso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En medio de incidentes, se inici\u00f3 a las 21:15 la sesi\u00f3n de esta mesa legislativa convocada por su presidenta la asamble\u00edsta corre\u00edsta, Pamela Aguirre, para tratar el juicio pol\u00edtico contra la fiscal Diana Salazar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La sesi\u00f3n fue convocada despu\u00e9s del fallo del juez de la Unidad Judicial de Quitumbe, Edgar Romero, que mult\u00f3 a miembros de la Comisi\u00f3n por no acatar la sentencia de reactivar los juicios pol\u00edticos contra tres exministros y funcionarios del gobierno de Guillermo Lasso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos juicios son contra el exministro de Finanzas, Pablo Arosemena; el exsecretario de la Administraci\u00f3n P\u00fablica, Sebasti\u00e1n Corral; y la extitular de la Secretar\u00eda de Educaci\u00f3n Superior, Andrea Montalvo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n, la convocatoria hecha por Aguirre incluye en su orden del d\u00eda conocer y calificar los pedidos de juicio pol\u00edtico contra la fiscal general del Estado, Diana Salazar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras los insultos e incidentes en el arranque de la sesi\u00f3n, Aguirre solicit\u00f3 al secretario relator Jairo Jarr\u00edn que diera lectura al articulado de la Ley Org\u00e1nica de la Funci\u00f3n Legislativa (LOFL), sobre las atribuciones y deberes de la Presidencia de la mesa legislativa. Tras la lectura la Presidenta dispuso avocar conocimiento y calificar el juicio pol\u00edtico contra Diana Salazar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embrago, el asamble\u00edsta de ADN, C\u00e9sar Umajinga, apel\u00f3 la Presidencia de Aguirre y con cinco votos a favor los asamble\u00edstas a fin al Gobierno tomaron la conducci\u00f3n de la Comisi\u00f3n de Fiscalizaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente encargado, el asamble\u00edsta Luis Alvarado, dispuso que se trate la sentencia judicial del juez Romero que saca del archivo los tres juicios pol\u00edticos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">#DianaSalazar #Comisi\u00f3ndeFiscalizaci\u00f3n #JuicioPol\u00edtico #AsambleaNacional #PamelaAguirre <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con 5 votos, la Comisi\u00f3n de Fiscalizaci\u00f3n de la Asamblea Nacional no calific\u00f3 el juicio pol\u00edtico a la fiscal general del Estado, Diana Salazar, cerca de la medianoche de este este lunes 9 de septiembre del 2024. Adem\u00e1s, retom\u00f3 los juicios pol\u00edticos contra tres exministros del r\u00e9gimen de Guillermo Lasso. En medio de incidentes, se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6776,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52],"tags":[],"class_list":["post-6775","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comisi\u00f3n de Fiscalizaci\u00f3n de la Asamblea archiv\u00f3 el juicio pol\u00edtico contra la fiscal general Diana Salazar - 92.5 FOREVER Radio<\/title>\n<meta name=\"description\" content=\"Con 5 votos, la Comisi\u00f3n de Fiscalizaci\u00f3n de la Asamblea Nacional no calific\u00f3 el juicio pol\u00edtico a la fiscal general del Estado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comisi\u00f3n de Fiscalizaci\u00f3n de la Asamblea archiv\u00f3 el juicio pol\u00edtico contra la fiscal general Diana Salazar - 92.5 FOREVER Radio\" \/>\n<meta property=\"og:description\" content=\"Con 5 votos, la Comisi\u00f3n de Fiscalizaci\u00f3n de la Asamblea Nacional no calific\u00f3 el juicio pol\u00edtico a la fiscal general del Estado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\/\" \/>\n<meta property=\"og:site_name\" content=\"92.5 FOREVER Radio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063550693491\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-10T18:18:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-10T18:18:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/09\/DianaSalazar-ComisiondeFiscalizacion-JuicioPolitico-AsambleaNacional-PamelaAguirre-ForeverInforma-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"865\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ricardo Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@925forever\" \/>\n<meta name=\"twitter:site\" content=\"@925forever\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\\\/\"},\"author\":{\"name\":\"Ricardo Rodriguez\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/person\\\/2f679dd16f889ac00df6e7b648062a01\"},\"headline\":\"Comisi\u00f3n de Fiscalizaci\u00f3n de la Asamblea archiv\u00f3 el juicio pol\u00edtico contra la fiscal general Diana Salazar\",\"datePublished\":\"2024-09-10T18:18:40+00:00\",\"dateModified\":\"2024-09-10T18:18:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\\\/\"},\"wordCount\":361,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/DianaSalazar-ComisiondeFiscalizacion-JuicioPolitico-AsambleaNacional-PamelaAguirre-ForeverInforma-.png\",\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\\\/\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\\\/\",\"name\":\"Comisi\u00f3n de Fiscalizaci\u00f3n de la Asamblea archiv\u00f3 el juicio pol\u00edtico contra la fiscal general Diana Salazar - 92.5 FOREVER Radio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/DianaSalazar-ComisiondeFiscalizacion-JuicioPolitico-AsambleaNacional-PamelaAguirre-ForeverInforma-.png\",\"datePublished\":\"2024-09-10T18:18:40+00:00\",\"dateModified\":\"2024-09-10T18:18:41+00:00\",\"description\":\"Con 5 votos, la Comisi\u00f3n de Fiscalizaci\u00f3n de la Asamblea Nacional no calific\u00f3 el juicio pol\u00edtico a la fiscal general del Estado.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/DianaSalazar-ComisiondeFiscalizacion-JuicioPolitico-AsambleaNacional-PamelaAguirre-ForeverInforma-.png\",\"contentUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/DianaSalazar-ComisiondeFiscalizacion-JuicioPolitico-AsambleaNacional-PamelaAguirre-ForeverInforma-.png\",\"width\":1280,\"height\":865},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/politica\\\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comisi\u00f3n de Fiscalizaci\u00f3n de la Asamblea archiv\u00f3 el juicio pol\u00edtico contra la fiscal general Diana Salazar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\",\"name\":\"92.5 FOREVER Radio\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\",\"name\":\"92.5 FOREVER Radio\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-logo-forever.png\",\"contentUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-logo-forever.png\",\"width\":180,\"height\":154,\"caption\":\"92.5 FOREVER Radio\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100063550693491\",\"https:\\\/\\\/x.com\\\/925forever\",\"https:\\\/\\\/www.instagram.com\\\/radioforever925\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/person\\\/2f679dd16f889ac00df6e7b648062a01\",\"name\":\"Ricardo Rodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"caption\":\"Ricardo Rodriguez\"},\"sameAs\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\"],\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/author\\\/superdmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comisi\u00f3n de Fiscalizaci\u00f3n de la Asamblea archiv\u00f3 el juicio pol\u00edtico contra la fiscal general Diana Salazar - 92.5 FOREVER Radio","description":"Con 5 votos, la Comisi\u00f3n de Fiscalizaci\u00f3n de la Asamblea Nacional no calific\u00f3 el juicio pol\u00edtico a la fiscal general del Estado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\/","og_locale":"es_ES","og_type":"article","og_title":"Comisi\u00f3n de Fiscalizaci\u00f3n de la Asamblea archiv\u00f3 el juicio pol\u00edtico contra la fiscal general Diana Salazar - 92.5 FOREVER Radio","og_description":"Con 5 votos, la Comisi\u00f3n de Fiscalizaci\u00f3n de la Asamblea Nacional no calific\u00f3 el juicio pol\u00edtico a la fiscal general del Estado.","og_url":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\/","og_site_name":"92.5 FOREVER Radio","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063550693491","article_published_time":"2024-09-10T18:18:40+00:00","article_modified_time":"2024-09-10T18:18:41+00:00","og_image":[{"width":1280,"height":865,"url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/09\/DianaSalazar-ComisiondeFiscalizacion-JuicioPolitico-AsambleaNacional-PamelaAguirre-ForeverInforma-.png","type":"image\/png"}],"author":"Ricardo Rodriguez","twitter_card":"summary_large_image","twitter_creator":"@925forever","twitter_site":"@925forever","twitter_misc":{"Escrito por":"Ricardo Rodriguez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\/#article","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\/"},"author":{"name":"Ricardo Rodriguez","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01"},"headline":"Comisi\u00f3n de Fiscalizaci\u00f3n de la Asamblea archiv\u00f3 el juicio pol\u00edtico contra la fiscal general Diana Salazar","datePublished":"2024-09-10T18:18:40+00:00","dateModified":"2024-09-10T18:18:41+00:00","mainEntityOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\/"},"wordCount":361,"commentCount":0,"publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/09\/DianaSalazar-ComisiondeFiscalizacion-JuicioPolitico-AsambleaNacional-PamelaAguirre-ForeverInforma-.png","articleSection":["Pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/foreverfutbol.com.ec\/radio\/politica\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\/","name":"Comisi\u00f3n de Fiscalizaci\u00f3n de la Asamblea archiv\u00f3 el juicio pol\u00edtico contra la fiscal general Diana Salazar - 92.5 FOREVER Radio","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\/#primaryimage"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/09\/DianaSalazar-ComisiondeFiscalizacion-JuicioPolitico-AsambleaNacional-PamelaAguirre-ForeverInforma-.png","datePublished":"2024-09-10T18:18:40+00:00","dateModified":"2024-09-10T18:18:41+00:00","description":"Con 5 votos, la Comisi\u00f3n de Fiscalizaci\u00f3n de la Asamblea Nacional no calific\u00f3 el juicio pol\u00edtico a la fiscal general del Estado.","breadcrumb":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/foreverfutbol.com.ec\/radio\/politica\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\/#primaryimage","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/09\/DianaSalazar-ComisiondeFiscalizacion-JuicioPolitico-AsambleaNacional-PamelaAguirre-ForeverInforma-.png","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/09\/DianaSalazar-ComisiondeFiscalizacion-JuicioPolitico-AsambleaNacional-PamelaAguirre-ForeverInforma-.png","width":1280,"height":865},{"@type":"BreadcrumbList","@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/comision-de-fiscalizacion-de-la-asamblea-archivo-el-juicio-politico-contra-la-fiscal-general-diana-salazar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/foreverfutbol.com.ec\/radio\/"},{"@type":"ListItem","position":2,"name":"Comisi\u00f3n de Fiscalizaci\u00f3n de la Asamblea archiv\u00f3 el juicio pol\u00edtico contra la fiscal general Diana Salazar"}]},{"@type":"WebSite","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website","url":"https:\/\/foreverfutbol.com.ec\/radio\/","name":"92.5 FOREVER Radio","description":"","publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/foreverfutbol.com.ec\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization","name":"92.5 FOREVER Radio","url":"https:\/\/foreverfutbol.com.ec\/radio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","width":180,"height":154,"caption":"92.5 FOREVER Radio"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063550693491","https:\/\/x.com\/925forever","https:\/\/www.instagram.com\/radioforever925\/"]},{"@type":"Person","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01","name":"Ricardo Rodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","caption":"Ricardo Rodriguez"},"sameAs":["https:\/\/foreverfutbol.com.ec\/radio"],"url":"https:\/\/foreverfutbol.com.ec\/radio\/author\/superdmin\/"}]}},"_links":{"self":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/6775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/comments?post=6775"}],"version-history":[{"count":1,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/6775\/revisions"}],"predecessor-version":[{"id":6777,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/6775\/revisions\/6777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media\/6776"}],"wp:attachment":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media?parent=6775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/categories?post=6775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/tags?post=6775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}