{"id":6615,"date":"2024-08-30T14:44:57","date_gmt":"2024-08-30T19:44:57","guid":{"rendered":"https:\/\/foreverfutbol.com.ec\/radio\/?p=6615"},"modified":"2024-08-30T16:33:29","modified_gmt":"2024-08-30T21:33:29","slug":"me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador","status":"publish","type":"post","link":"https:\/\/foreverfutbol.com.ec\/radio\/deportes\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\/","title":{"rendered":"\u00abMe falta Campana en esta lista\u00bb: Felipe Caicedo reacciona a la lista de convocados de la Selecci\u00f3n de Ecuador"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Sebasti\u00e1n Beccacece present\u00f3 su primera lista de convocados a la selecci\u00f3n ecuatoriana la ma\u00f1ana de este viernes, 30 de agosto, para los duelos ante Brasil y Per\u00fa por las eliminatorias sudamericanas al Mundial 2026.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez confirmada la n\u00f3mina, uno de los hist\u00f3ricos de la Tricolor se pronunci\u00f3 sobre la misma, reclamando la ausencia de un jugador en espec\u00edfico: Leonardo Campana. El artillero opin\u00f3 en su cuenta de X sobre el no llamado del futbolista del Inter Miami de forma contundente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abMe falta Campana en esa lista\u201d, escribi\u00f3 el atacante, uni\u00e9ndose a los cientos de aficionados que en las \u00faltimas convocatorias han solicitado la presencia del centrodelantero del cuadro del sur de Florida<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1079\" height=\"1075\" src=\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/08\/GWQDLQHXgAAI6N3.jpeg\" alt=\"\" class=\"wp-image-6621\" srcset=\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/08\/GWQDLQHXgAAI6N3.jpeg 1079w, https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/08\/GWQDLQHXgAAI6N3-768x765.jpeg 768w, https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/08\/GWQDLQHXgAAI6N3-100x100.jpeg 100w\" sizes=\"auto, (max-width: 1079px) 100vw, 1079px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">#FelipeCaicedo #LeoCampana #Campana #Sebasti\u00e1nBeccacece #LaTri #Ecuador <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sebasti\u00e1n Beccacece present\u00f3 su primera lista de convocados a la selecci\u00f3n ecuatoriana la ma\u00f1ana de este viernes, 30 de agosto, para los duelos ante Brasil y Per\u00fa por las eliminatorias sudamericanas al Mundial 2026. Una vez confirmada la n\u00f3mina, uno de los hist\u00f3ricos de la Tricolor se pronunci\u00f3 sobre la misma, reclamando la ausencia de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6616,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62],"tags":[],"class_list":["post-6615","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Felipe Caicedo reacciona a la lista de convocados de la Tri<\/title>\n<meta name=\"description\" content=\"&quot;Me falta Campana en esta lista&quot;: Felipe Caicedo reacciona a la lista de convocados de la Selecci\u00f3n de Ecuador.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/foreverfutbol.com.ec\/radio\/deportes\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Felipe Caicedo reacciona a la lista de convocados de la Tri\" \/>\n<meta property=\"og:description\" content=\"&quot;Me falta Campana en esta lista&quot;: Felipe Caicedo reacciona a la lista de convocados de la Selecci\u00f3n de Ecuador.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/deportes\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\/\" \/>\n<meta property=\"og:site_name\" content=\"92.5 FOREVER Radio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063550693491\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-30T19:44:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-30T21:33:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/08\/FelipeCaicedo-LeoCampana-Campana-SebastianBeccacece-LaTri-Ecuador-foreverinforma.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"865\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ricardo Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@925forever\" \/>\n<meta name=\"twitter:site\" content=\"@925forever\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/deportes\\\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/deportes\\\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\\\/\"},\"author\":{\"name\":\"Ricardo Rodriguez\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/person\\\/2f679dd16f889ac00df6e7b648062a01\"},\"headline\":\"\u00abMe falta Campana en esta lista\u00bb: Felipe Caicedo reacciona a la lista de convocados de la Selecci\u00f3n de Ecuador\",\"datePublished\":\"2024-08-30T19:44:57+00:00\",\"dateModified\":\"2024-08-30T21:33:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/deportes\\\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\\\/\"},\"wordCount\":145,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/deportes\\\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/FelipeCaicedo-LeoCampana-Campana-SebastianBeccacece-LaTri-Ecuador-foreverinforma.png\",\"articleSection\":[\"Deportes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/deportes\\\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/deportes\\\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\\\/\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/deportes\\\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\\\/\",\"name\":\"Felipe Caicedo reacciona a la lista de convocados de la Tri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/deportes\\\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/deportes\\\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/FelipeCaicedo-LeoCampana-Campana-SebastianBeccacece-LaTri-Ecuador-foreverinforma.png\",\"datePublished\":\"2024-08-30T19:44:57+00:00\",\"dateModified\":\"2024-08-30T21:33:29+00:00\",\"description\":\"\\\"Me falta Campana en esta lista\\\": Felipe Caicedo reacciona a la lista de convocados de la Selecci\u00f3n de Ecuador.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/deportes\\\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/deportes\\\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/deportes\\\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\\\/#primaryimage\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/FelipeCaicedo-LeoCampana-Campana-SebastianBeccacece-LaTri-Ecuador-foreverinforma.png\",\"contentUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/FelipeCaicedo-LeoCampana-Campana-SebastianBeccacece-LaTri-Ecuador-foreverinforma.png\",\"width\":1280,\"height\":865},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/deportes\\\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abMe falta Campana en esta lista\u00bb: Felipe Caicedo reacciona a la lista de convocados de la Selecci\u00f3n de Ecuador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\",\"name\":\"92.5 FOREVER Radio\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\",\"name\":\"92.5 FOREVER Radio\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-logo-forever.png\",\"contentUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-logo-forever.png\",\"width\":180,\"height\":154,\"caption\":\"92.5 FOREVER Radio\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100063550693491\",\"https:\\\/\\\/x.com\\\/925forever\",\"https:\\\/\\\/www.instagram.com\\\/radioforever925\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/person\\\/2f679dd16f889ac00df6e7b648062a01\",\"name\":\"Ricardo Rodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"caption\":\"Ricardo Rodriguez\"},\"sameAs\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\"],\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/author\\\/superdmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Felipe Caicedo reacciona a la lista de convocados de la Tri","description":"\"Me falta Campana en esta lista\": Felipe Caicedo reacciona a la lista de convocados de la Selecci\u00f3n de Ecuador.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/foreverfutbol.com.ec\/radio\/deportes\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\/","og_locale":"es_ES","og_type":"article","og_title":"Felipe Caicedo reacciona a la lista de convocados de la Tri","og_description":"\"Me falta Campana en esta lista\": Felipe Caicedo reacciona a la lista de convocados de la Selecci\u00f3n de Ecuador.","og_url":"https:\/\/foreverfutbol.com.ec\/radio\/deportes\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\/","og_site_name":"92.5 FOREVER Radio","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063550693491","article_published_time":"2024-08-30T19:44:57+00:00","article_modified_time":"2024-08-30T21:33:29+00:00","og_image":[{"width":1280,"height":865,"url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/08\/FelipeCaicedo-LeoCampana-Campana-SebastianBeccacece-LaTri-Ecuador-foreverinforma.png","type":"image\/png"}],"author":"Ricardo Rodriguez","twitter_card":"summary_large_image","twitter_creator":"@925forever","twitter_site":"@925forever","twitter_misc":{"Escrito por":"Ricardo Rodriguez","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/foreverfutbol.com.ec\/radio\/deportes\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\/#article","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/deportes\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\/"},"author":{"name":"Ricardo Rodriguez","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01"},"headline":"\u00abMe falta Campana en esta lista\u00bb: Felipe Caicedo reacciona a la lista de convocados de la Selecci\u00f3n de Ecuador","datePublished":"2024-08-30T19:44:57+00:00","dateModified":"2024-08-30T21:33:29+00:00","mainEntityOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/deportes\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\/"},"wordCount":145,"commentCount":0,"publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/deportes\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/08\/FelipeCaicedo-LeoCampana-Campana-SebastianBeccacece-LaTri-Ecuador-foreverinforma.png","articleSection":["Deportes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/foreverfutbol.com.ec\/radio\/deportes\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/foreverfutbol.com.ec\/radio\/deportes\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/deportes\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\/","name":"Felipe Caicedo reacciona a la lista de convocados de la Tri","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/deportes\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\/#primaryimage"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/deportes\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/08\/FelipeCaicedo-LeoCampana-Campana-SebastianBeccacece-LaTri-Ecuador-foreverinforma.png","datePublished":"2024-08-30T19:44:57+00:00","dateModified":"2024-08-30T21:33:29+00:00","description":"\"Me falta Campana en esta lista\": Felipe Caicedo reacciona a la lista de convocados de la Selecci\u00f3n de Ecuador.","breadcrumb":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/deportes\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/foreverfutbol.com.ec\/radio\/deportes\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/deportes\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\/#primaryimage","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/08\/FelipeCaicedo-LeoCampana-Campana-SebastianBeccacece-LaTri-Ecuador-foreverinforma.png","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/08\/FelipeCaicedo-LeoCampana-Campana-SebastianBeccacece-LaTri-Ecuador-foreverinforma.png","width":1280,"height":865},{"@type":"BreadcrumbList","@id":"https:\/\/foreverfutbol.com.ec\/radio\/deportes\/me-falta-campana-en-esta-lista-felipe-caicedo-reacciona-a-la-lista-de-convocados-de-la-seleccion-de-ecuador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/foreverfutbol.com.ec\/radio\/"},{"@type":"ListItem","position":2,"name":"\u00abMe falta Campana en esta lista\u00bb: Felipe Caicedo reacciona a la lista de convocados de la Selecci\u00f3n de Ecuador"}]},{"@type":"WebSite","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website","url":"https:\/\/foreverfutbol.com.ec\/radio\/","name":"92.5 FOREVER Radio","description":"","publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/foreverfutbol.com.ec\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization","name":"92.5 FOREVER Radio","url":"https:\/\/foreverfutbol.com.ec\/radio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","width":180,"height":154,"caption":"92.5 FOREVER Radio"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063550693491","https:\/\/x.com\/925forever","https:\/\/www.instagram.com\/radioforever925\/"]},{"@type":"Person","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01","name":"Ricardo Rodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","caption":"Ricardo Rodriguez"},"sameAs":["https:\/\/foreverfutbol.com.ec\/radio"],"url":"https:\/\/foreverfutbol.com.ec\/radio\/author\/superdmin\/"}]}},"_links":{"self":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/6615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/comments?post=6615"}],"version-history":[{"count":4,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/6615\/revisions"}],"predecessor-version":[{"id":6622,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/6615\/revisions\/6622"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media\/6616"}],"wp:attachment":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media?parent=6615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/categories?post=6615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/tags?post=6615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}