{"id":6600,"date":"2024-08-30T12:17:58","date_gmt":"2024-08-30T17:17:58","guid":{"rendered":"https:\/\/foreverfutbol.com.ec\/radio\/?p=6600"},"modified":"2024-08-30T12:18:45","modified_gmt":"2024-08-30T17:18:45","slug":"rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo","status":"publish","type":"post","link":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\/","title":{"rendered":"Rector del CNE de Venezuela desmiente a Nicol\u00e1s Maduro sobre supuesto hackeo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En medio de la incertidumbre por lo que sucede en Venezuela, en las \u00faltimas horas uno de los rectores del CNE, Juan Carlos Del Pino, concedi\u00f3 una entrevista en Noticias Caracol en donde revela m\u00e1s detalles de lo que sucedi\u00f3 en las elecciones del 28 de julio se\u00f1aladas como fraudulentas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTengo elementos de car\u00e1cter t\u00e9cnico en los que queda clara evidencia que el hackeo pudo no haberse producido nunca. La oposici\u00f3n tiene esos elementos, tiene esas actas firmadas por todos los auditores\u201d, manifest\u00f3 Delpino. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, revel\u00f3 detalles de lo que sucedi\u00f3 al interior del CNE el d\u00eda de las elecciones: \u201c(\u2026) a la hora que yo recibo una invitaci\u00f3n a una reuni\u00f3n, digamos t\u00e9cnica, en donde se me comunica que se ha producido un hackeo al sistema y que eso ha impedido que contin\u00fae la transmisi\u00f3n y que se cuenta con una transmisi\u00f3n del 58%, se me pide subir a totalizaci\u00f3n y yo me niego, sencillamente porque el 58% no es lo que tradicionalmente se hace. T\u00fa declaras el resultado despu\u00e9s de transitado por encima del 95%, como era la costumbre, de tal manera que la tendencia hubiese sido irreversible\u201d, dijo Delpino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAl final las tendencias no estaban totalmente verificadas y t\u00fa no pod\u00edas constatar que era irreversible, a eso no me arriesgaba\u201d, agreg\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">#Venezuela #JuanCarlosDelPino #CNE #Nicol\u00e1sMaduro <\/p>\n","protected":false},"excerpt":{"rendered":"<p>En medio de la incertidumbre por lo que sucede en Venezuela, en las \u00faltimas horas uno de los rectores del CNE, Juan Carlos Del Pino, concedi\u00f3 una entrevista en Noticias Caracol en donde revela m\u00e1s detalles de lo que sucedi\u00f3 en las elecciones del 28 de julio se\u00f1aladas como fraudulentas. \u201cTengo elementos de car\u00e1cter t\u00e9cnico [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6602,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54],"tags":[],"class_list":["post-6600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rector del CNE de Venezuela desmiente a Maduro sobre hackeo<\/title>\n<meta name=\"description\" content=\"\u201cTengo elementos de car\u00e1cter t\u00e9cnico en los que queda clara evidencia que el hackeo pudo no haberse producido nunca&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rector del CNE de Venezuela desmiente a Maduro sobre hackeo\" \/>\n<meta property=\"og:description\" content=\"\u201cTengo elementos de car\u00e1cter t\u00e9cnico en los que queda clara evidencia que el hackeo pudo no haberse producido nunca&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\/\" \/>\n<meta property=\"og:site_name\" content=\"92.5 FOREVER Radio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063550693491\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-30T17:17:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-30T17:18:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/08\/Venezuela-JuanCarlosDelPino-CNE-NicolasMaduro-foreverinforma.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"865\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ricardo Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@925forever\" \/>\n<meta name=\"twitter:site\" content=\"@925forever\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/internacional\\\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/internacional\\\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\\\/\"},\"author\":{\"name\":\"Ricardo Rodriguez\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/person\\\/2f679dd16f889ac00df6e7b648062a01\"},\"headline\":\"Rector del CNE de Venezuela desmiente a Nicol\u00e1s Maduro sobre supuesto hackeo\",\"datePublished\":\"2024-08-30T17:17:58+00:00\",\"dateModified\":\"2024-08-30T17:18:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/internacional\\\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\\\/\"},\"wordCount\":243,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/internacional\\\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Venezuela-JuanCarlosDelPino-CNE-NicolasMaduro-foreverinforma.png\",\"articleSection\":[\"Internacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/internacional\\\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/internacional\\\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\\\/\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/internacional\\\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\\\/\",\"name\":\"Rector del CNE de Venezuela desmiente a Maduro sobre hackeo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/internacional\\\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/internacional\\\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Venezuela-JuanCarlosDelPino-CNE-NicolasMaduro-foreverinforma.png\",\"datePublished\":\"2024-08-30T17:17:58+00:00\",\"dateModified\":\"2024-08-30T17:18:45+00:00\",\"description\":\"\u201cTengo elementos de car\u00e1cter t\u00e9cnico en los que queda clara evidencia que el hackeo pudo no haberse producido nunca\\\".\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/internacional\\\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/internacional\\\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/internacional\\\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Venezuela-JuanCarlosDelPino-CNE-NicolasMaduro-foreverinforma.png\",\"contentUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Venezuela-JuanCarlosDelPino-CNE-NicolasMaduro-foreverinforma.png\",\"width\":1280,\"height\":865},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/internacional\\\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rector del CNE de Venezuela desmiente a Nicol\u00e1s Maduro sobre supuesto hackeo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\",\"name\":\"92.5 FOREVER Radio\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\",\"name\":\"92.5 FOREVER Radio\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-logo-forever.png\",\"contentUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-logo-forever.png\",\"width\":180,\"height\":154,\"caption\":\"92.5 FOREVER Radio\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100063550693491\",\"https:\\\/\\\/x.com\\\/925forever\",\"https:\\\/\\\/www.instagram.com\\\/radioforever925\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/person\\\/2f679dd16f889ac00df6e7b648062a01\",\"name\":\"Ricardo Rodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"caption\":\"Ricardo Rodriguez\"},\"sameAs\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\"],\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/author\\\/superdmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rector del CNE de Venezuela desmiente a Maduro sobre hackeo","description":"\u201cTengo elementos de car\u00e1cter t\u00e9cnico en los que queda clara evidencia que el hackeo pudo no haberse producido nunca\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\/","og_locale":"es_ES","og_type":"article","og_title":"Rector del CNE de Venezuela desmiente a Maduro sobre hackeo","og_description":"\u201cTengo elementos de car\u00e1cter t\u00e9cnico en los que queda clara evidencia que el hackeo pudo no haberse producido nunca\".","og_url":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\/","og_site_name":"92.5 FOREVER Radio","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063550693491","article_published_time":"2024-08-30T17:17:58+00:00","article_modified_time":"2024-08-30T17:18:45+00:00","og_image":[{"width":1280,"height":865,"url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/08\/Venezuela-JuanCarlosDelPino-CNE-NicolasMaduro-foreverinforma.png","type":"image\/png"}],"author":"Ricardo Rodriguez","twitter_card":"summary_large_image","twitter_creator":"@925forever","twitter_site":"@925forever","twitter_misc":{"Escrito por":"Ricardo Rodriguez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\/#article","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\/"},"author":{"name":"Ricardo Rodriguez","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01"},"headline":"Rector del CNE de Venezuela desmiente a Nicol\u00e1s Maduro sobre supuesto hackeo","datePublished":"2024-08-30T17:17:58+00:00","dateModified":"2024-08-30T17:18:45+00:00","mainEntityOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\/"},"wordCount":243,"commentCount":0,"publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/08\/Venezuela-JuanCarlosDelPino-CNE-NicolasMaduro-foreverinforma.png","articleSection":["Internacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/foreverfutbol.com.ec\/radio\/internacional\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\/","name":"Rector del CNE de Venezuela desmiente a Maduro sobre hackeo","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\/#primaryimage"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/08\/Venezuela-JuanCarlosDelPino-CNE-NicolasMaduro-foreverinforma.png","datePublished":"2024-08-30T17:17:58+00:00","dateModified":"2024-08-30T17:18:45+00:00","description":"\u201cTengo elementos de car\u00e1cter t\u00e9cnico en los que queda clara evidencia que el hackeo pudo no haberse producido nunca\".","breadcrumb":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/foreverfutbol.com.ec\/radio\/internacional\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\/#primaryimage","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/08\/Venezuela-JuanCarlosDelPino-CNE-NicolasMaduro-foreverinforma.png","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/08\/Venezuela-JuanCarlosDelPino-CNE-NicolasMaduro-foreverinforma.png","width":1280,"height":865},{"@type":"BreadcrumbList","@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/rector-del-cne-de-venezuela-desmiente-a-nicolas-maduro-sobre-supuesto-hackeo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/foreverfutbol.com.ec\/radio\/"},{"@type":"ListItem","position":2,"name":"Rector del CNE de Venezuela desmiente a Nicol\u00e1s Maduro sobre supuesto hackeo"}]},{"@type":"WebSite","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website","url":"https:\/\/foreverfutbol.com.ec\/radio\/","name":"92.5 FOREVER Radio","description":"","publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/foreverfutbol.com.ec\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization","name":"92.5 FOREVER Radio","url":"https:\/\/foreverfutbol.com.ec\/radio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","width":180,"height":154,"caption":"92.5 FOREVER Radio"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063550693491","https:\/\/x.com\/925forever","https:\/\/www.instagram.com\/radioforever925\/"]},{"@type":"Person","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01","name":"Ricardo Rodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","caption":"Ricardo Rodriguez"},"sameAs":["https:\/\/foreverfutbol.com.ec\/radio"],"url":"https:\/\/foreverfutbol.com.ec\/radio\/author\/superdmin\/"}]}},"_links":{"self":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/6600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/comments?post=6600"}],"version-history":[{"count":1,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/6600\/revisions"}],"predecessor-version":[{"id":6603,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/6600\/revisions\/6603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media\/6602"}],"wp:attachment":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media?parent=6600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/categories?post=6600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/tags?post=6600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}