{"id":6502,"date":"2024-08-23T15:30:19","date_gmt":"2024-08-23T20:30:19","guid":{"rendered":"https:\/\/foreverfutbol.com.ec\/radio\/?p=6502"},"modified":"2024-08-23T15:30:21","modified_gmt":"2024-08-23T20:30:21","slug":"decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos","status":"publish","type":"post","link":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\/","title":{"rendered":"Decomisan dos toneladas de droga que eran transportadas en tres lanchas; hay siete detenidos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Durante un operativo en conjunto con la Armada, fueron aprehendidos 7 sujetos e interceptadas 3 embarcaciones de pesca artesanal en las que se transportaban aproximadamente 1.340 bloques de sustancias sujetas a fiscalizaci\u00f3n, m\u00e1s de dos toneladas de droga, a 60 millas n\u00e1uticas del Puerto de Manta, en la provincia de Manab\u00ed. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las tres lanchas pesqueras que fueron interceptadas por la Armada del Ecuador el 22 de agosto de 2024, a 60 millas n\u00e1uticas de las costas de Manta, salieron desde Pedernales, al norte de la provincia, con destino a M\u00e9xico y Guatemala, seg\u00fan informaci\u00f3n de la Polic\u00eda Nacional.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En dos de las embarcaciones hallaron coca\u00edna, al menos 1.340 bloques (tienen unos 6 identificativos distintos). La instituci\u00f3n del orden cifra en m\u00e1s de dos toneladas el cargamento. Adem\u00e1s, siete personas fueron capturadas: cinco de Jaramij\u00f3 (Manab\u00ed) y dos de Santa Elena.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Indicios:<br>-45 sacos de yute que conten\u00edan 2&#8217;265.300 gramos de coca\u00edna<br>-3 celulares<br>-1 tel\u00e9fono satelital<br>-Dinero en efectivo y otros indicios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">#Manta #Manab\u00ed #Jaramij\u00f3 #SantaElena #ArmadadelEcuador #decomisodedroga <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante un operativo en conjunto con la Armada, fueron aprehendidos 7 sujetos e interceptadas 3 embarcaciones de pesca artesanal en las que se transportaban aproximadamente 1.340 bloques de sustancias sujetas a fiscalizaci\u00f3n, m\u00e1s de dos toneladas de droga, a 60 millas n\u00e1uticas del Puerto de Manta, en la provincia de Manab\u00ed. Las tres lanchas pesqueras [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6503,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51],"tags":[],"class_list":["post-6502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sucesos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Incautan 2 toneladas de droga que eran transportadas en lanchas<\/title>\n<meta name=\"description\" content=\"Durante un operativo en conjunto con la Armada, fueron aprehendidos 7 sujetos e interceptadas 3 embarcaciones de pesca artesanal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Incautan 2 toneladas de droga que eran transportadas en lanchas\" \/>\n<meta property=\"og:description\" content=\"Durante un operativo en conjunto con la Armada, fueron aprehendidos 7 sujetos e interceptadas 3 embarcaciones de pesca artesanal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\/\" \/>\n<meta property=\"og:site_name\" content=\"92.5 FOREVER Radio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063550693491\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-23T20:30:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-23T20:30:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/08\/Manta-Manabi-Jaramijo-SantaElena-ArmadadelEcuador-decomisodedroga-foreverinforma.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"865\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ricardo Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@925forever\" \/>\n<meta name=\"twitter:site\" content=\"@925forever\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/sucesos\\\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/sucesos\\\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\\\/\"},\"author\":{\"name\":\"Ricardo Rodriguez\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/person\\\/2f679dd16f889ac00df6e7b648062a01\"},\"headline\":\"Decomisan dos toneladas de droga que eran transportadas en tres lanchas; hay siete detenidos\",\"datePublished\":\"2024-08-23T20:30:19+00:00\",\"dateModified\":\"2024-08-23T20:30:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/sucesos\\\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\\\/\"},\"wordCount\":184,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/sucesos\\\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Manta-Manabi-Jaramijo-SantaElena-ArmadadelEcuador-decomisodedroga-foreverinforma.png\",\"articleSection\":[\"Sucesos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/sucesos\\\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/sucesos\\\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\\\/\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/sucesos\\\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\\\/\",\"name\":\"Incautan 2 toneladas de droga que eran transportadas en lanchas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/sucesos\\\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/sucesos\\\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Manta-Manabi-Jaramijo-SantaElena-ArmadadelEcuador-decomisodedroga-foreverinforma.png\",\"datePublished\":\"2024-08-23T20:30:19+00:00\",\"dateModified\":\"2024-08-23T20:30:21+00:00\",\"description\":\"Durante un operativo en conjunto con la Armada, fueron aprehendidos 7 sujetos e interceptadas 3 embarcaciones de pesca artesanal.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/sucesos\\\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/sucesos\\\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/sucesos\\\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Manta-Manabi-Jaramijo-SantaElena-ArmadadelEcuador-decomisodedroga-foreverinforma.png\",\"contentUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Manta-Manabi-Jaramijo-SantaElena-ArmadadelEcuador-decomisodedroga-foreverinforma.png\",\"width\":1280,\"height\":865},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/sucesos\\\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Decomisan dos toneladas de droga que eran transportadas en tres lanchas; hay siete detenidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\",\"name\":\"92.5 FOREVER Radio\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\",\"name\":\"92.5 FOREVER Radio\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-logo-forever.png\",\"contentUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-logo-forever.png\",\"width\":180,\"height\":154,\"caption\":\"92.5 FOREVER Radio\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100063550693491\",\"https:\\\/\\\/x.com\\\/925forever\",\"https:\\\/\\\/www.instagram.com\\\/radioforever925\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/person\\\/2f679dd16f889ac00df6e7b648062a01\",\"name\":\"Ricardo Rodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"caption\":\"Ricardo Rodriguez\"},\"sameAs\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\"],\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/author\\\/superdmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Incautan 2 toneladas de droga que eran transportadas en lanchas","description":"Durante un operativo en conjunto con la Armada, fueron aprehendidos 7 sujetos e interceptadas 3 embarcaciones de pesca artesanal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\/","og_locale":"es_ES","og_type":"article","og_title":"Incautan 2 toneladas de droga que eran transportadas en lanchas","og_description":"Durante un operativo en conjunto con la Armada, fueron aprehendidos 7 sujetos e interceptadas 3 embarcaciones de pesca artesanal.","og_url":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\/","og_site_name":"92.5 FOREVER Radio","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063550693491","article_published_time":"2024-08-23T20:30:19+00:00","article_modified_time":"2024-08-23T20:30:21+00:00","og_image":[{"width":1280,"height":865,"url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/08\/Manta-Manabi-Jaramijo-SantaElena-ArmadadelEcuador-decomisodedroga-foreverinforma.png","type":"image\/png"}],"author":"Ricardo Rodriguez","twitter_card":"summary_large_image","twitter_creator":"@925forever","twitter_site":"@925forever","twitter_misc":{"Escrito por":"Ricardo Rodriguez","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\/#article","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\/"},"author":{"name":"Ricardo Rodriguez","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01"},"headline":"Decomisan dos toneladas de droga que eran transportadas en tres lanchas; hay siete detenidos","datePublished":"2024-08-23T20:30:19+00:00","dateModified":"2024-08-23T20:30:21+00:00","mainEntityOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\/"},"wordCount":184,"commentCount":0,"publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/08\/Manta-Manabi-Jaramijo-SantaElena-ArmadadelEcuador-decomisodedroga-foreverinforma.png","articleSection":["Sucesos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\/","name":"Incautan 2 toneladas de droga que eran transportadas en lanchas","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\/#primaryimage"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/08\/Manta-Manabi-Jaramijo-SantaElena-ArmadadelEcuador-decomisodedroga-foreverinforma.png","datePublished":"2024-08-23T20:30:19+00:00","dateModified":"2024-08-23T20:30:21+00:00","description":"Durante un operativo en conjunto con la Armada, fueron aprehendidos 7 sujetos e interceptadas 3 embarcaciones de pesca artesanal.","breadcrumb":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\/#primaryimage","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/08\/Manta-Manabi-Jaramijo-SantaElena-ArmadadelEcuador-decomisodedroga-foreverinforma.png","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/08\/Manta-Manabi-Jaramijo-SantaElena-ArmadadelEcuador-decomisodedroga-foreverinforma.png","width":1280,"height":865},{"@type":"BreadcrumbList","@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/decomisan-dos-toneladas-de-droga-que-eran-transportadas-en-tres-lanchas-hay-siete-detenidos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/foreverfutbol.com.ec\/radio\/"},{"@type":"ListItem","position":2,"name":"Decomisan dos toneladas de droga que eran transportadas en tres lanchas; hay siete detenidos"}]},{"@type":"WebSite","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website","url":"https:\/\/foreverfutbol.com.ec\/radio\/","name":"92.5 FOREVER Radio","description":"","publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/foreverfutbol.com.ec\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization","name":"92.5 FOREVER Radio","url":"https:\/\/foreverfutbol.com.ec\/radio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","width":180,"height":154,"caption":"92.5 FOREVER Radio"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063550693491","https:\/\/x.com\/925forever","https:\/\/www.instagram.com\/radioforever925\/"]},{"@type":"Person","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01","name":"Ricardo Rodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","caption":"Ricardo Rodriguez"},"sameAs":["https:\/\/foreverfutbol.com.ec\/radio"],"url":"https:\/\/foreverfutbol.com.ec\/radio\/author\/superdmin\/"}]}},"_links":{"self":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/6502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/comments?post=6502"}],"version-history":[{"count":1,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/6502\/revisions"}],"predecessor-version":[{"id":6504,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/6502\/revisions\/6504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media\/6503"}],"wp:attachment":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media?parent=6502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/categories?post=6502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/tags?post=6502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}