{"id":6042,"date":"2024-07-24T12:13:22","date_gmt":"2024-07-24T17:13:22","guid":{"rendered":"https:\/\/foreverfutbol.com.ec\/radio\/?p=6042"},"modified":"2024-07-24T12:23:11","modified_gmt":"2024-07-24T17:23:11","slug":"tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas","status":"publish","type":"post","link":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/","title":{"rendered":"Tragedia en Nepal: avi\u00f3n se estrell\u00f3 y se incendi\u00f3 mientras despegaba; hay 18 personas fallecidas"},"content":{"rendered":"\n<p>18 personas murieron cuando un avi\u00f3n de pasajeros regional perteneciente a Saurya Airlines se estrell\u00f3 y se incendi\u00f3 mientras despegaba de la capital Katmand\u00fa este mi\u00e9rcoles, 24 de julio de 2024, dijeron las autoridades.<\/p>\n\n\n\n<p>La aeronave, en la que viajaban dos tripulantes y 17 t\u00e9cnicos, se dirig\u00eda al nuevo aeropuerto de Pokhara, en Nepal, inaugurado en enero y equipado con hangares para el mantenimiento de aviones, indicaron.<\/p>\n\n\n\n<p>\u00abS\u00f3lo el capit\u00e1n fue rescatado con vida y est\u00e1 recibiendo tratamiento en un hospital\u00bb, dijo Tej Bahadur Poudyal, portavoz del Aeropuerto Internacional Tribhuvan, de Katmand\u00fa. En im\u00e1genes compartidas por el ej\u00e9rcito pod\u00eda verse el fuselaje del avi\u00f3n partido y carbonizado.La industria a\u00e9rea nepal\u00ed creci\u00f3 con fuerza en los \u00faltimos a\u00f1os, lo que ha facilitado el transporte de personas y mercanc\u00eda a zonas de dif\u00edcil acceso, as\u00ed como monta\u00f1istas.<\/p>\n\n\n\n<p>Sin embargo, se ha visto lastrada por sus deficientes normas de seguridad. La Uni\u00f3n Europea prohibi\u00f3 a todas las aerol\u00edneas de Nepal sobrevolar su espacio a\u00e9reo por motivos de seguridad.<\/p>\n\n\n\n<p>El \u00faltimo accidente de envergadura de un avi\u00f3n comercial en el pa\u00eds se produjo en enero de 2023, cuando un aparato de Yeti Airlines se estrell\u00f3 al tratar de aterrizar en Pokhara. Las 72 personas a bordo fallecieron.<\/p>\n\n\n\n<p>#Nepal #aeropuertodePokhara #Pokhara #SauryaAirlines #18muertos <\/p>\n","protected":false},"excerpt":{"rendered":"<p>18 personas murieron cuando un avi\u00f3n de pasajeros regional perteneciente a Saurya Airlines se estrell\u00f3 y se incendi\u00f3 mientras despegaba de la capital Katmand\u00fa este mi\u00e9rcoles, 24 de julio de 2024, dijeron las autoridades. La aeronave, en la que viajaban dos tripulantes y 17 t\u00e9cnicos, se dirig\u00eda al nuevo aeropuerto de Pokhara, en Nepal, inaugurado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6043,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54],"tags":[],"class_list":["post-6042","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tragedia en Nepal: 18 muertos mientras despegaba un avi\u00f3n<\/title>\n<meta name=\"description\" content=\"Tragedia en Nepal: avi\u00f3n se estrell\u00f3 y se incendi\u00f3 mientras despegaba; hay 18 personas fallecidas y un herido.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tragedia en Nepal: 18 muertos mientras despegaba un avi\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Tragedia en Nepal: avi\u00f3n se estrell\u00f3 y se incendi\u00f3 mientras despegaba; hay 18 personas fallecidas y un herido.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/\" \/>\n<meta property=\"og:site_name\" content=\"92.5 FOREVER Radio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063550693491\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-24T17:13:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-24T17:23:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/07\/Nepal-aeropuertodePokhara-Pokhara-SauryaAirlines-18muertos-RadioForever.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"865\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ricardo Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@925forever\" \/>\n<meta name=\"twitter:site\" content=\"@925forever\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/\"},\"author\":{\"name\":\"Ricardo Rodriguez\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01\"},\"headline\":\"Tragedia en Nepal: avi\u00f3n se estrell\u00f3 y se incendi\u00f3 mientras despegaba; hay 18 personas fallecidas\",\"datePublished\":\"2024-07-24T17:13:22+00:00\",\"dateModified\":\"2024-07-24T17:23:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/\"},\"wordCount\":238,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#organization\"},\"image\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/07\/Nepal-aeropuertodePokhara-Pokhara-SauryaAirlines-18muertos-RadioForever.png\",\"articleSection\":[\"Internacional\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/\",\"url\":\"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/\",\"name\":\"Tragedia en Nepal: 18 muertos mientras despegaba un avi\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/07\/Nepal-aeropuertodePokhara-Pokhara-SauryaAirlines-18muertos-RadioForever.png\",\"datePublished\":\"2024-07-24T17:13:22+00:00\",\"dateModified\":\"2024-07-24T17:23:11+00:00\",\"description\":\"Tragedia en Nepal: avi\u00f3n se estrell\u00f3 y se incendi\u00f3 mientras despegaba; hay 18 personas fallecidas y un herido.\",\"breadcrumb\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/#primaryimage\",\"url\":\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/07\/Nepal-aeropuertodePokhara-Pokhara-SauryaAirlines-18muertos-RadioForever.png\",\"contentUrl\":\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/07\/Nepal-aeropuertodePokhara-Pokhara-SauryaAirlines-18muertos-RadioForever.png\",\"width\":1280,\"height\":865},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/foreverfutbol.com.ec\/radio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tragedia en Nepal: avi\u00f3n se estrell\u00f3 y se incendi\u00f3 mientras despegaba; hay 18 personas fallecidas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#website\",\"url\":\"https:\/\/foreverfutbol.com.ec\/radio\/\",\"name\":\"92.5 FOREVER Radio\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/foreverfutbol.com.ec\/radio\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#organization\",\"name\":\"92.5 FOREVER Radio\",\"url\":\"https:\/\/foreverfutbol.com.ec\/radio\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png\",\"contentUrl\":\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png\",\"width\":180,\"height\":154,\"caption\":\"92.5 FOREVER Radio\"},\"image\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100063550693491\",\"https:\/\/x.com\/925forever\",\"https:\/\/www.instagram.com\/radioforever925\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01\",\"name\":\"Ricardo Rodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/e40e2129642cc37300c493eac481301df5ff08b78ad01765fa6145185e95fb7e?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e40e2129642cc37300c493eac481301df5ff08b78ad01765fa6145185e95fb7e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e40e2129642cc37300c493eac481301df5ff08b78ad01765fa6145185e95fb7e?s=96&d=mm&r=g\",\"caption\":\"Ricardo Rodriguez\"},\"sameAs\":[\"https:\/\/foreverfutbol.com.ec\/radio\"],\"url\":\"https:\/\/foreverfutbol.com.ec\/radio\/author\/superdmin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tragedia en Nepal: 18 muertos mientras despegaba un avi\u00f3n","description":"Tragedia en Nepal: avi\u00f3n se estrell\u00f3 y se incendi\u00f3 mientras despegaba; hay 18 personas fallecidas y un herido.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/","og_locale":"es_ES","og_type":"article","og_title":"Tragedia en Nepal: 18 muertos mientras despegaba un avi\u00f3n","og_description":"Tragedia en Nepal: avi\u00f3n se estrell\u00f3 y se incendi\u00f3 mientras despegaba; hay 18 personas fallecidas y un herido.","og_url":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/","og_site_name":"92.5 FOREVER Radio","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063550693491","article_published_time":"2024-07-24T17:13:22+00:00","article_modified_time":"2024-07-24T17:23:11+00:00","og_image":[{"width":1280,"height":865,"url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/07\/Nepal-aeropuertodePokhara-Pokhara-SauryaAirlines-18muertos-RadioForever.png","type":"image\/png"}],"author":"Ricardo Rodriguez","twitter_card":"summary_large_image","twitter_creator":"@925forever","twitter_site":"@925forever","twitter_misc":{"Escrito por":"Ricardo Rodriguez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/#article","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/"},"author":{"name":"Ricardo Rodriguez","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01"},"headline":"Tragedia en Nepal: avi\u00f3n se estrell\u00f3 y se incendi\u00f3 mientras despegaba; hay 18 personas fallecidas","datePublished":"2024-07-24T17:13:22+00:00","dateModified":"2024-07-24T17:23:11+00:00","mainEntityOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/"},"wordCount":238,"commentCount":0,"publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/07\/Nepal-aeropuertodePokhara-Pokhara-SauryaAirlines-18muertos-RadioForever.png","articleSection":["Internacional"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/","name":"Tragedia en Nepal: 18 muertos mientras despegaba un avi\u00f3n","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/#primaryimage"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/07\/Nepal-aeropuertodePokhara-Pokhara-SauryaAirlines-18muertos-RadioForever.png","datePublished":"2024-07-24T17:13:22+00:00","dateModified":"2024-07-24T17:23:11+00:00","description":"Tragedia en Nepal: avi\u00f3n se estrell\u00f3 y se incendi\u00f3 mientras despegaba; hay 18 personas fallecidas y un herido.","breadcrumb":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/#primaryimage","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/07\/Nepal-aeropuertodePokhara-Pokhara-SauryaAirlines-18muertos-RadioForever.png","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/07\/Nepal-aeropuertodePokhara-Pokhara-SauryaAirlines-18muertos-RadioForever.png","width":1280,"height":865},{"@type":"BreadcrumbList","@id":"https:\/\/foreverfutbol.com.ec\/radio\/internacional\/tragedia-en-nepal-avion-se-estrello-y-se-incendio-mientras-despegaba-hay-18-personas-fallecidas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/foreverfutbol.com.ec\/radio\/"},{"@type":"ListItem","position":2,"name":"Tragedia en Nepal: avi\u00f3n se estrell\u00f3 y se incendi\u00f3 mientras despegaba; hay 18 personas fallecidas"}]},{"@type":"WebSite","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website","url":"https:\/\/foreverfutbol.com.ec\/radio\/","name":"92.5 FOREVER Radio","description":"","publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/foreverfutbol.com.ec\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization","name":"92.5 FOREVER Radio","url":"https:\/\/foreverfutbol.com.ec\/radio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","width":180,"height":154,"caption":"92.5 FOREVER Radio"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063550693491","https:\/\/x.com\/925forever","https:\/\/www.instagram.com\/radioforever925\/"]},{"@type":"Person","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01","name":"Ricardo Rodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e40e2129642cc37300c493eac481301df5ff08b78ad01765fa6145185e95fb7e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e40e2129642cc37300c493eac481301df5ff08b78ad01765fa6145185e95fb7e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e40e2129642cc37300c493eac481301df5ff08b78ad01765fa6145185e95fb7e?s=96&d=mm&r=g","caption":"Ricardo Rodriguez"},"sameAs":["https:\/\/foreverfutbol.com.ec\/radio"],"url":"https:\/\/foreverfutbol.com.ec\/radio\/author\/superdmin\/"}]}},"_links":{"self":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/6042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/comments?post=6042"}],"version-history":[{"count":1,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/6042\/revisions"}],"predecessor-version":[{"id":6044,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/6042\/revisions\/6044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media\/6043"}],"wp:attachment":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media?parent=6042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/categories?post=6042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/tags?post=6042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}