{"id":5623,"date":"2024-07-02T15:07:22","date_gmt":"2024-07-02T20:07:22","guid":{"rendered":"https:\/\/foreverfutbol.com.ec\/radio\/?p=5623"},"modified":"2024-07-02T15:07:23","modified_gmt":"2024-07-02T20:07:23","slug":"noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva","status":"publish","type":"post","link":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/","title":{"rendered":"Noboa pide a Banecuador perdonar deudas de hasta $ 5.000 que est\u00e9n en etapa de coactiva"},"content":{"rendered":"\n<p>Las deudas con Banecuador en etapa de coactiva de hasta $ 5.000 ser\u00e1n perdonadas. El presidente Daniel Noboa emiti\u00f3 el Decreto Ejecutivo 317 en el que se faculta al Directorio y Gerencia General de esa entidad financiera el implementar la medida.<\/p>\n\n\n\n<p>\u201cHe dado la disposici\u00f3n a Banecuador que no te cobre m\u00e1s, que todas las operaciones coactivas de hasta $ 5.000 desde 2016 hasta la fecha sean perdonadas\u201d, dijo Noboa en un video publicado esta ma\u00f1ana.<\/p>\n\n\n\n<p>El Decreto establece \u201cla condonaci\u00f3n de cr\u00e9ditos coactivados en fase de apremio y calificados con riesgo E\u201d. Estos no deber\u00e1n tener garant\u00edas reales para su ejecuci\u00f3n. El monto l\u00edmite establecido incluye el capital, sus interese y otros costos y comisiones.\u201c<\/p>\n\n\n\n<p>El documento tambi\u00e9n establece una fecha l\u00edmite. La medida aplicar\u00e1 para los cr\u00e9ditos hasta la fecha en la que se publique el Decreto en el Registro Oficial. Este fue emitido con fecha 2 de julio de 2024.<\/p>\n\n\n\n<p>Banecuador se encargar\u00e1 de las acciones administrativas, financieras y contables, adem\u00e1s de emitir los actos administrativos e informar al Servicio de Rentas Internas (SRI). <\/p>\n\n\n\n<p>#Ecuador #BanEcuador #DanielNoboa #coactivas <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las deudas con Banecuador en etapa de coactiva de hasta $ 5.000 ser\u00e1n perdonadas. El presidente Daniel Noboa emiti\u00f3 el Decreto Ejecutivo 317 en el que se faculta al Directorio y Gerencia General de esa entidad financiera el implementar la medida. \u201cHe dado la disposici\u00f3n a Banecuador que no te cobre m\u00e1s, que todas las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5624,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52],"tags":[],"class_list":["post-5623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Noboa pide a Banecuador perdonar deudas de hasta $ 5.000<\/title>\n<meta name=\"description\" content=\"Las deudas con Banecuador en etapa de coactiva de hasta $ 5.000 ser\u00e1n perdonadas. El presidente Daniel Noboa emiti\u00f3 el Decreto Ejecutivo 317\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Noboa pide a Banecuador perdonar deudas de hasta $ 5.000\" \/>\n<meta property=\"og:description\" content=\"Las deudas con Banecuador en etapa de coactiva de hasta $ 5.000 ser\u00e1n perdonadas. El presidente Daniel Noboa emiti\u00f3 el Decreto Ejecutivo 317\" \/>\n<meta property=\"og:url\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/\" \/>\n<meta property=\"og:site_name\" content=\"92.5 FOREVER Radio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063550693491\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-02T20:07:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-02T20:07:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/07\/Ecuador-BanEcuador-DanielNoboa-coactivas-radioForever.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"865\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ricardo Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@925forever\" \/>\n<meta name=\"twitter:site\" content=\"@925forever\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/\"},\"author\":{\"name\":\"Ricardo Rodriguez\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01\"},\"headline\":\"Noboa pide a Banecuador perdonar deudas de hasta $ 5.000 que est\u00e9n en etapa de coactiva\",\"datePublished\":\"2024-07-02T20:07:22+00:00\",\"dateModified\":\"2024-07-02T20:07:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/\"},\"wordCount\":202,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#organization\"},\"image\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/07\/Ecuador-BanEcuador-DanielNoboa-coactivas-radioForever.png\",\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/\",\"url\":\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/\",\"name\":\"Noboa pide a Banecuador perdonar deudas de hasta $ 5.000\",\"isPartOf\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/07\/Ecuador-BanEcuador-DanielNoboa-coactivas-radioForever.png\",\"datePublished\":\"2024-07-02T20:07:22+00:00\",\"dateModified\":\"2024-07-02T20:07:23+00:00\",\"description\":\"Las deudas con Banecuador en etapa de coactiva de hasta $ 5.000 ser\u00e1n perdonadas. El presidente Daniel Noboa emiti\u00f3 el Decreto Ejecutivo 317\",\"breadcrumb\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/#primaryimage\",\"url\":\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/07\/Ecuador-BanEcuador-DanielNoboa-coactivas-radioForever.png\",\"contentUrl\":\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/07\/Ecuador-BanEcuador-DanielNoboa-coactivas-radioForever.png\",\"width\":1280,\"height\":865},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/foreverfutbol.com.ec\/radio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noboa pide a Banecuador perdonar deudas de hasta $ 5.000 que est\u00e9n en etapa de coactiva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#website\",\"url\":\"https:\/\/foreverfutbol.com.ec\/radio\/\",\"name\":\"92.5 FOREVER Radio\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/foreverfutbol.com.ec\/radio\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#organization\",\"name\":\"92.5 FOREVER Radio\",\"url\":\"https:\/\/foreverfutbol.com.ec\/radio\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png\",\"contentUrl\":\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png\",\"width\":180,\"height\":154,\"caption\":\"92.5 FOREVER Radio\"},\"image\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100063550693491\",\"https:\/\/x.com\/925forever\",\"https:\/\/www.instagram.com\/radioforever925\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01\",\"name\":\"Ricardo Rodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/e40e2129642cc37300c493eac481301df5ff08b78ad01765fa6145185e95fb7e?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e40e2129642cc37300c493eac481301df5ff08b78ad01765fa6145185e95fb7e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e40e2129642cc37300c493eac481301df5ff08b78ad01765fa6145185e95fb7e?s=96&d=mm&r=g\",\"caption\":\"Ricardo Rodriguez\"},\"sameAs\":[\"https:\/\/foreverfutbol.com.ec\/radio\"],\"url\":\"https:\/\/foreverfutbol.com.ec\/radio\/author\/superdmin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Noboa pide a Banecuador perdonar deudas de hasta $ 5.000","description":"Las deudas con Banecuador en etapa de coactiva de hasta $ 5.000 ser\u00e1n perdonadas. El presidente Daniel Noboa emiti\u00f3 el Decreto Ejecutivo 317","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/","og_locale":"es_ES","og_type":"article","og_title":"Noboa pide a Banecuador perdonar deudas de hasta $ 5.000","og_description":"Las deudas con Banecuador en etapa de coactiva de hasta $ 5.000 ser\u00e1n perdonadas. El presidente Daniel Noboa emiti\u00f3 el Decreto Ejecutivo 317","og_url":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/","og_site_name":"92.5 FOREVER Radio","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063550693491","article_published_time":"2024-07-02T20:07:22+00:00","article_modified_time":"2024-07-02T20:07:23+00:00","og_image":[{"width":1280,"height":865,"url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/07\/Ecuador-BanEcuador-DanielNoboa-coactivas-radioForever.png","type":"image\/png"}],"author":"Ricardo Rodriguez","twitter_card":"summary_large_image","twitter_creator":"@925forever","twitter_site":"@925forever","twitter_misc":{"Escrito por":"Ricardo Rodriguez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/#article","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/"},"author":{"name":"Ricardo Rodriguez","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01"},"headline":"Noboa pide a Banecuador perdonar deudas de hasta $ 5.000 que est\u00e9n en etapa de coactiva","datePublished":"2024-07-02T20:07:22+00:00","dateModified":"2024-07-02T20:07:23+00:00","mainEntityOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/"},"wordCount":202,"commentCount":0,"publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/07\/Ecuador-BanEcuador-DanielNoboa-coactivas-radioForever.png","articleSection":["Pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/","name":"Noboa pide a Banecuador perdonar deudas de hasta $ 5.000","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/#primaryimage"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/07\/Ecuador-BanEcuador-DanielNoboa-coactivas-radioForever.png","datePublished":"2024-07-02T20:07:22+00:00","dateModified":"2024-07-02T20:07:23+00:00","description":"Las deudas con Banecuador en etapa de coactiva de hasta $ 5.000 ser\u00e1n perdonadas. El presidente Daniel Noboa emiti\u00f3 el Decreto Ejecutivo 317","breadcrumb":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/#primaryimage","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/07\/Ecuador-BanEcuador-DanielNoboa-coactivas-radioForever.png","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/07\/Ecuador-BanEcuador-DanielNoboa-coactivas-radioForever.png","width":1280,"height":865},{"@type":"BreadcrumbList","@id":"https:\/\/foreverfutbol.com.ec\/radio\/politica\/noboa-pide-a-banecuador-perdonar-deudas-de-hasta-5-000-que-esten-en-etapa-de-coactiva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/foreverfutbol.com.ec\/radio\/"},{"@type":"ListItem","position":2,"name":"Noboa pide a Banecuador perdonar deudas de hasta $ 5.000 que est\u00e9n en etapa de coactiva"}]},{"@type":"WebSite","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website","url":"https:\/\/foreverfutbol.com.ec\/radio\/","name":"92.5 FOREVER Radio","description":"","publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/foreverfutbol.com.ec\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization","name":"92.5 FOREVER Radio","url":"https:\/\/foreverfutbol.com.ec\/radio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","width":180,"height":154,"caption":"92.5 FOREVER Radio"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063550693491","https:\/\/x.com\/925forever","https:\/\/www.instagram.com\/radioforever925\/"]},{"@type":"Person","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01","name":"Ricardo Rodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e40e2129642cc37300c493eac481301df5ff08b78ad01765fa6145185e95fb7e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e40e2129642cc37300c493eac481301df5ff08b78ad01765fa6145185e95fb7e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e40e2129642cc37300c493eac481301df5ff08b78ad01765fa6145185e95fb7e?s=96&d=mm&r=g","caption":"Ricardo Rodriguez"},"sameAs":["https:\/\/foreverfutbol.com.ec\/radio"],"url":"https:\/\/foreverfutbol.com.ec\/radio\/author\/superdmin\/"}]}},"_links":{"self":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/5623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/comments?post=5623"}],"version-history":[{"count":1,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/5623\/revisions"}],"predecessor-version":[{"id":5625,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/5623\/revisions\/5625"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media\/5624"}],"wp:attachment":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media?parent=5623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/categories?post=5623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/tags?post=5623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}