{"id":5444,"date":"2024-06-21T16:20:49","date_gmt":"2024-06-21T21:20:49","guid":{"rendered":"https:\/\/foreverfutbol.com.ec\/radio\/?p=5444"},"modified":"2024-06-21T16:21:05","modified_gmt":"2024-06-21T21:21:05","slug":"la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados","status":"publish","type":"post","link":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/","title":{"rendered":"La Fiscal\u00eda solicita a la morgue de Guayaquil que practique un estudio de ADN a los cad\u00e1veres no identificados"},"content":{"rendered":"\n<p>Mediante un acto administrativo urgente, la Fiscal\u00eda de Guayas solicit\u00f3 a la Coordinadora T\u00e9cnica de Servicios de Medicina Legal y Ciencias Forenses que practique un estudio de ADN de los cad\u00e1veres no identificados, para su posterior liberaci\u00f3n e inhumaci\u00f3n, como medida para descongestionar este centro forense, que present\u00f3 \u2013d\u00edas atr\u00e1s\u2013 una acumulaci\u00f3n inusitada de cuerpos en descomposici\u00f3n de personas no identificadas, que se manten\u00edan en contenedores refrigerados con mal funcionamiento, provocando insalubridad en el sector suroeste de Guayaquil.<\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p lang=\"es\" dir=\"ltr\"><a href=\"https:\/\/twitter.com\/hashtag\/ATENCI%C3%93N?src=hash&amp;ref_src=twsrc%5Etfw\">#ATENCI\u00d3N<\/a> | <a href=\"https:\/\/twitter.com\/hashtag\/Guayas?src=hash&amp;ref_src=twsrc%5Etfw\">#Guayas<\/a>: mediante acto administrativo, <a href=\"https:\/\/twitter.com\/hashtag\/Fiscal%C3%ADaEc?src=hash&amp;ref_src=twsrc%5Etfw\">#Fiscal\u00edaEc<\/a> solicita la liberaci\u00f3n de cad\u00e1veres no identificados y un examen de perfil de ADN a cuerpos abandonados en el Centro Forense de <a href=\"https:\/\/twitter.com\/hashtag\/Guayaquil?src=hash&amp;ref_src=twsrc%5Etfw\">#Guayaquil<\/a>. <br><br>Detalles\u2b07\ufe0f<a href=\"https:\/\/t.co\/HlRAXRuETg\">https:\/\/t.co\/HlRAXRuETg<\/a> <a href=\"https:\/\/t.co\/KttBaqFpvk\">pic.twitter.com\/KttBaqFpvk<\/a><\/p>&mdash; Fiscal\u00eda Ecuador (@FiscaliaEcuador) <a href=\"https:\/\/twitter.com\/FiscaliaEcuador\/status\/1804233723283403245?ref_src=twsrc%5Etfw\">June 21, 2024<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<p>La medida fue tomada tras una reuni\u00f3n sostenida con el Ministerio del Interior y la Gobernaci\u00f3n, ante la emergencia sanitaria que pudo provocar lo ocurrido, debido al mal funcionamiento de los contenedores de refrigeraci\u00f3n que aglomeraban m\u00e1s de 200 cad\u00e1veres no retirados ni identificados.<\/p>\n\n\n\n<p>La fiscal de la Unidad Especializada de Actuaciones Administrativas de esta ciudad, Tania Gualoto, solicit\u00f3 el 20 de junio del a\u00f1o en curso que se practique el estudio de ADN, con el objeto de obtener el perfil de las muestras recolectadas en el procedimiento de autopsia y proceder al cotejamiento con la base de datos de familiares de personas desaparecidas del Laboratorio de Gen\u00e9tica Forense.<\/p>\n\n\n\n<p>Adem\u00e1s, dispuso la liberaci\u00f3n de los cad\u00e1veres no identificados considerados aptos para el proceso de inhumaci\u00f3n, que cuenten con el Informe Estad\u00edstico de Defunci\u00f3n General (IEDG) y el Protocolo de Autopsia que establece su posible causa de muerte.<\/p>\n\n\n\n<p>Con esta disposici\u00f3n, sesenta y un cad\u00e1veres \u2013de mujeres y hombres\u2013, partes de piezas anat\u00f3micas y restos \u00f3seos podr\u00edan inhumarse en las pr\u00f3ximas semanas, dependiendo del tr\u00e1mite por parte de la Direcci\u00f3n de Medicina Legal y Ciencias Forenses.<\/p>\n\n\n\n<p>#Ecuador #Guayaquil #morguedeGuayaquil #medicinalegal #urgente #Guayas <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mediante un acto administrativo urgente, la Fiscal\u00eda de Guayas solicit\u00f3 a la Coordinadora T\u00e9cnica de Servicios de Medicina Legal y Ciencias Forenses que practique un estudio de ADN de los cad\u00e1veres no identificados, para su posterior liberaci\u00f3n e inhumaci\u00f3n, como medida para descongestionar este centro forense, que present\u00f3 \u2013d\u00edas atr\u00e1s\u2013 una acumulaci\u00f3n inusitada de cuerpos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5448,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51],"tags":[],"class_list":["post-5444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sucesos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fiscal\u00eda solicita a la morgue de Guayaquil identificar cuerpos<\/title>\n<meta name=\"description\" content=\"Fiscal\u00eda solicit\u00f3 a la morgue de Guayaquil que practique un estudio de ADN a los cad\u00e1veres no identificados, para su posterior liberaci\u00f3n e inhumaci\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda solicita a la morgue de Guayaquil identificar cuerpos\" \/>\n<meta property=\"og:description\" content=\"Fiscal\u00eda solicit\u00f3 a la morgue de Guayaquil que practique un estudio de ADN a los cad\u00e1veres no identificados, para su posterior liberaci\u00f3n e inhumaci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/\" \/>\n<meta property=\"og:site_name\" content=\"92.5 FOREVER Radio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063550693491\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-21T21:20:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-21T21:21:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/06\/laboratorio-criminalistica.png\" \/>\n\t<meta property=\"og:image:width\" content=\"675\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ricardo Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@925forever\" \/>\n<meta name=\"twitter:site\" content=\"@925forever\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/\"},\"author\":{\"name\":\"Ricardo Rodriguez\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01\"},\"headline\":\"La Fiscal\u00eda solicita a la morgue de Guayaquil que practique un estudio de ADN a los cad\u00e1veres no identificados\",\"datePublished\":\"2024-06-21T21:20:49+00:00\",\"dateModified\":\"2024-06-21T21:21:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/\"},\"wordCount\":366,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#organization\"},\"image\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/06\/laboratorio-criminalistica.png\",\"articleSection\":[\"Sucesos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/\",\"url\":\"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/\",\"name\":\"Fiscal\u00eda solicita a la morgue de Guayaquil identificar cuerpos\",\"isPartOf\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/06\/laboratorio-criminalistica.png\",\"datePublished\":\"2024-06-21T21:20:49+00:00\",\"dateModified\":\"2024-06-21T21:21:05+00:00\",\"description\":\"Fiscal\u00eda solicit\u00f3 a la morgue de Guayaquil que practique un estudio de ADN a los cad\u00e1veres no identificados, para su posterior liberaci\u00f3n e inhumaci\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/#primaryimage\",\"url\":\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/06\/laboratorio-criminalistica.png\",\"contentUrl\":\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/06\/laboratorio-criminalistica.png\",\"width\":675,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/foreverfutbol.com.ec\/radio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Fiscal\u00eda solicita a la morgue de Guayaquil que practique un estudio de ADN a los cad\u00e1veres no identificados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#website\",\"url\":\"https:\/\/foreverfutbol.com.ec\/radio\/\",\"name\":\"92.5 FOREVER Radio\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/foreverfutbol.com.ec\/radio\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#organization\",\"name\":\"92.5 FOREVER Radio\",\"url\":\"https:\/\/foreverfutbol.com.ec\/radio\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png\",\"contentUrl\":\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png\",\"width\":180,\"height\":154,\"caption\":\"92.5 FOREVER Radio\"},\"image\":{\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100063550693491\",\"https:\/\/x.com\/925forever\",\"https:\/\/www.instagram.com\/radioforever925\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01\",\"name\":\"Ricardo Rodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/e40e2129642cc37300c493eac481301df5ff08b78ad01765fa6145185e95fb7e?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e40e2129642cc37300c493eac481301df5ff08b78ad01765fa6145185e95fb7e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e40e2129642cc37300c493eac481301df5ff08b78ad01765fa6145185e95fb7e?s=96&d=mm&r=g\",\"caption\":\"Ricardo Rodriguez\"},\"sameAs\":[\"https:\/\/foreverfutbol.com.ec\/radio\"],\"url\":\"https:\/\/foreverfutbol.com.ec\/radio\/author\/superdmin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda solicita a la morgue de Guayaquil identificar cuerpos","description":"Fiscal\u00eda solicit\u00f3 a la morgue de Guayaquil que practique un estudio de ADN a los cad\u00e1veres no identificados, para su posterior liberaci\u00f3n e inhumaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/","og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda solicita a la morgue de Guayaquil identificar cuerpos","og_description":"Fiscal\u00eda solicit\u00f3 a la morgue de Guayaquil que practique un estudio de ADN a los cad\u00e1veres no identificados, para su posterior liberaci\u00f3n e inhumaci\u00f3n","og_url":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/","og_site_name":"92.5 FOREVER Radio","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063550693491","article_published_time":"2024-06-21T21:20:49+00:00","article_modified_time":"2024-06-21T21:21:05+00:00","og_image":[{"width":675,"height":360,"url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/06\/laboratorio-criminalistica.png","type":"image\/png"}],"author":"Ricardo Rodriguez","twitter_card":"summary_large_image","twitter_creator":"@925forever","twitter_site":"@925forever","twitter_misc":{"Escrito por":"Ricardo Rodriguez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/#article","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/"},"author":{"name":"Ricardo Rodriguez","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01"},"headline":"La Fiscal\u00eda solicita a la morgue de Guayaquil que practique un estudio de ADN a los cad\u00e1veres no identificados","datePublished":"2024-06-21T21:20:49+00:00","dateModified":"2024-06-21T21:21:05+00:00","mainEntityOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/"},"wordCount":366,"commentCount":0,"publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/06\/laboratorio-criminalistica.png","articleSection":["Sucesos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/","name":"Fiscal\u00eda solicita a la morgue de Guayaquil identificar cuerpos","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/#primaryimage"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/06\/laboratorio-criminalistica.png","datePublished":"2024-06-21T21:20:49+00:00","dateModified":"2024-06-21T21:21:05+00:00","description":"Fiscal\u00eda solicit\u00f3 a la morgue de Guayaquil que practique un estudio de ADN a los cad\u00e1veres no identificados, para su posterior liberaci\u00f3n e inhumaci\u00f3n","breadcrumb":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/#primaryimage","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/06\/laboratorio-criminalistica.png","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/06\/laboratorio-criminalistica.png","width":675,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/foreverfutbol.com.ec\/radio\/sucesos\/la-fiscalia-solicita-a-la-morgue-de-guayaquil-que-practique-un-estudio-de-adn-a-los-cadaveres-no-identificados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/foreverfutbol.com.ec\/radio\/"},{"@type":"ListItem","position":2,"name":"La Fiscal\u00eda solicita a la morgue de Guayaquil que practique un estudio de ADN a los cad\u00e1veres no identificados"}]},{"@type":"WebSite","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website","url":"https:\/\/foreverfutbol.com.ec\/radio\/","name":"92.5 FOREVER Radio","description":"","publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/foreverfutbol.com.ec\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization","name":"92.5 FOREVER Radio","url":"https:\/\/foreverfutbol.com.ec\/radio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","width":180,"height":154,"caption":"92.5 FOREVER Radio"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063550693491","https:\/\/x.com\/925forever","https:\/\/www.instagram.com\/radioforever925\/"]},{"@type":"Person","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01","name":"Ricardo Rodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e40e2129642cc37300c493eac481301df5ff08b78ad01765fa6145185e95fb7e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e40e2129642cc37300c493eac481301df5ff08b78ad01765fa6145185e95fb7e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e40e2129642cc37300c493eac481301df5ff08b78ad01765fa6145185e95fb7e?s=96&d=mm&r=g","caption":"Ricardo Rodriguez"},"sameAs":["https:\/\/foreverfutbol.com.ec\/radio"],"url":"https:\/\/foreverfutbol.com.ec\/radio\/author\/superdmin\/"}]}},"_links":{"self":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/5444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/comments?post=5444"}],"version-history":[{"count":1,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/5444\/revisions"}],"predecessor-version":[{"id":5449,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/5444\/revisions\/5449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media\/5448"}],"wp:attachment":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media?parent=5444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/categories?post=5444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/tags?post=5444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}