{"id":14990,"date":"2025-05-12T14:57:49","date_gmt":"2025-05-12T19:57:49","guid":{"rendered":"https:\/\/foreverfutbol.com.ec\/radio\/?p=14990"},"modified":"2025-05-13T17:42:00","modified_gmt":"2025-05-13T22:42:00","slug":"enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz","status":"publish","type":"post","link":"https:\/\/foreverfutbol.com.ec\/radio\/editorial\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\/","title":{"rendered":"Enmendar y reformar la Constituci\u00f3n y leyes para reactivar la econom\u00eda y recuperar la paz."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Es la alternativa que se debe llevar a cabo en la nueva Asamblea Nacional con una mayor\u00eda que se sume solucionar los problemas de inseguridad y pobreza creados por la actual Constituci\u00f3n como dos gestiones y dos objetivos necesarios a corto plazo. Y dejar para el mediano y largo plazo la recuperaci\u00f3n de la institucionalidad y del estado de derecho para una Constituyente como valores democr\u00e1ticos perdidos desde la vigencia de la actual Constituci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para los objetivos de corto plazo existen dos gestiones: enmendar y reformar la Constituci\u00f3n y asegurar una Asamblea Nacional que garantice la gobernabilidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la primera gesti\u00f3n, se intent\u00f3 evitar los inconvenientes que conlleva la Asamblea Nacional Constituyente, a trav\u00e9s de una convocatoria con un texto previamente elaborado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero considerando que la Corte Constitucional con el Dictamen 10-24-RC\/25 del 1 de mayo de 2025 rechaz\u00f3 la propuesta de modificaci\u00f3n constitucional del ciudadano Galo Ortiz Pico en representaci\u00f3n de la corporaci\u00f3n de Docentes Investigadores del Ecuador (DINEC), junto con la Fundaci\u00f3n de Derechos de Inclusi\u00f3n y Consolidaci\u00f3n de Servicios Sociales (Fundaci\u00f3n) para convocar a una Asamblea Constituyente que apruebe un texto ya preelaborado. Con lo que queda ratificado que se debe cumplir los pasos del art\u00edculo 444 de la constituci\u00f3n:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>1. Consulta popular para aprobar la convocatoria a asamblea nacional constituyente;<\/li>\n\n\n\n<li>2. Elecci\u00f3n de asamble\u00edstas constituyentes;<\/li>\n\n\n\n<li>3. Refer\u00e9ndum para aprobar o rechazar el nuevo texto, como \u00fanica forma de Constituyente. Aunque esto signifique $200 millones de d\u00f3lares de costo, seg\u00fan estimaci\u00f3n de los entendidos, polarizaci\u00f3n pol\u00edtica; y paralizaci\u00f3n de inversiones y otros al menos por un a\u00f1o y medio hasta conocer las nuevas reglas del juego. Adem\u00e1s de un posible rechazo a las reformas si el Gobierno pierde capital pol\u00edtico hasta ese entonces<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Un tema que surge para el debate en una eventual Constituyente es la posibilidad de revisar los derechos incluidos en la actual desde el 2008. En ese sentido hay opiniones que dicen que todo derecho puede ser revisado al tratarse de refundar un Estado, salvo los fundamentales, mientras otros manifiestan que son irreversibles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante esto, queda una alternativa que ha sido apoyada por varios constitucionalista y que est\u00e1 tomando fuerza, que es aplicar las enmiendas, de acuerdo al Art. 441 y las reformas parciales, de acuerdo al art\u00edculo 442. Las enmiendas se har\u00edan en la Asamblea Nacional con la mayor\u00eda de la mitad m\u00e1s uno y las reformas de la misma forma y luego en refer\u00e9ndum, tomando menos de 150 d\u00edas o 5 meses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese caso, s\u00ed puede discutirse los temas con textos preelaborados o redactados como propuestas, para s\u00f3lo enmendar y reformar con el m\u00e9todo propuesto en base a textos previamente acordados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como concepto, la Constituyente, seg\u00fan el art\u00edculo 444 de la Constituci\u00f3n actual, dice: \u00abLa nueva Constituci\u00f3n, para su entrada en vigencia, requerir\u00e1 ser aprobada mediante refer\u00e9ndum con la mitad m\u00e1s uno de los votos v\u00e1lidos\u00bb. Con lo que se puede refundar al Estado como algunos la conciben. Es decir, tiene un poder amplio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su lado la enmienda de acuerdo al 441, s\u00f3lo se puede \u00abde uno o varios art\u00edculos de la Constituci\u00f3n que no altere su estructura fundamental, o el car\u00e1cter y elementos constitutivos del Estado, que no establezca restricciones a los derechos y garant\u00edas, o que no modifique el procedimiento de reforma de la Constituci\u00f3n\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte la reforma parcial, de acuerdo al 442, se aplica a lo que \u00abno suponga una restricci\u00f3n en los derechos y garant\u00edas constitucionales, ni modifique el procedimiento de reforma de la Constituci\u00f3n\u00bb. Con lo que s\u00ed se puede \u00abalterar la estructura fundamental o el car\u00e1cter y elementos constitutivos del Estado\u00bb; por ejemplo: regresar a tres funciones del Estado: Legislativo, Ejecutivo y Judicial y eliminar esa categor\u00eda a la de Transparencia y Electoral. As\u00ed como eliminar al Consejo de Participaci\u00f3n Ciudadana y Control Social y al Consejo de la Judicatura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las enmiendas y reformas ser\u00edan acogiendo lo que ya la Corte Constitucional aprob\u00f3 para estas dos modalidades en la consulta popular de Guillermo Lasso y de la \u00faltima de Daniel Noboa: En la primera, a Guillermo Lasso el 5 de febrero 2023 se le dijo no en todas las ocho preguntas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pregunta 1 &#8211; extradici\u00f3n, no, aunque a Noboa luego se le dijo s\u00ed;<\/li>\n\n\n\n<li>Pregunta 2 cambios en la fiscal\u00eda general del estado (independencia), no; Pregunta<\/li>\n\n\n\n<li>Pregunta 3 &#8211; reducci\u00f3n de asamble\u00edstas, no;<\/li>\n\n\n\n<li>Pregunta 4 &#8211; reducci\u00f3n de organizaciones pol\u00edticas;<\/li>\n\n\n\n<li>Pregunta 5 &#8211; cambio de facultad de designaci\u00f3n de autoridades de control desde el CPCCS a la asamblea nacional, no;<\/li>\n\n\n\n<li>Pregunta 6 &#8211; cambio de forma de elecci\u00f3n de los vocales del CPCCS, desde el voto popular a la Asamblea;<\/li>\n\n\n\n<li>Pregunta 7 &#8211; Subsistema de protecci\u00f3n h\u00eddrica incorporando el agua, no;<\/li>\n\n\n\n<li>pregunta 8 &#8211; compensaci\u00f3n por servicios ambientales a favor de las comunidades, no.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Y a Daniel Noboa en abril 2024: se le aprob\u00f3 el apoyo de las FFAA a la Polic\u00eda Nacional; la extradici\u00f3n; creaci\u00f3n de judicaturas especializadas en materia constitucional; revisi\u00f3n de competencias de las FFAA; incremento de penas; reformas al COIP; prohibici\u00f3n de tenencia de armas oficiales; darle uso a las armas incautadas; y la expropiaci\u00f3n de bienes incautados. Pero la mayor\u00eda le dijo no al arbitraje internacional y al trabajo por horas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero \u00bfc\u00f3mo asegurar la aprobaci\u00f3n en la nueva Asamblea Nacional? Este mi\u00e9rcoles 14 de mayo se instalar\u00e1 la nueva asamblea nacional. Al momento se considera que ADN tendr\u00eda la mayor\u00eda para captar dignidades, el CAL y las Comisiones, contando con sus 66 asamble\u00edstas, a los que sumar\u00edan 4 votos del PSC, 4 independientes y 3 por lo menos de pachakutik, con lo que al menos, si no se suma otra voluntad m\u00e1s, llegar\u00edan a los 77 votos justos. Pero, \u00bfcree que esto est\u00e1 consolidado inclusive con posibilidad de incremento o habr\u00e1 cambios de \u00faltima hora? Para llegar al consenso y gobernabilidad el pedido ciudadano es mejorar la calidad de los asamble\u00edstas, que no puede ser igual o peor que las dos \u00faltimas. Cuya calificaci\u00f3n es muy paup\u00e9rrima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero, \u00bfc\u00f3mo asegurar el mejoramiento de la calidad del debate, si a\u00fan se sigue votando por listas e incluso se han reelegido asamble\u00edstas que demostraron baj\u00edsima calidad? Esta semana ser\u00e1 crucial par el futuro de nuestro pa\u00eds. Es cierto que debemos ir paso a paso. Hasta aqu\u00ed el triunfo electoral de Daniel Noboa y Mar\u00eda Jos\u00e9 Pinto ha sido ratificado por el CNE y el TCE luego de las objeciones sin sentido de RC5; el viaje del presidente Noboa y su comitiva a Europa y Asia abre nuevas perspectivas muy positivas en materia de inversi\u00f3n, comerci\u00f3, tecnolog\u00eda, educaci\u00f3n, agricultura, seguridad ciudadana y jur\u00eddica. Pero resta la concreci\u00f3n del ambiente propicio para que todo eso se haga realidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Primero, asegurar la paz y la gobernabilidad, a la par mejorar el empleo con enmiendas y reformas a la Constituci\u00f3n y a las leyes y posteriormente recuperar la institucionalidad con reformas mucho m\u00e1s profundas para rescatar al pa\u00eds de los candados constitucionales de la actual Constituci\u00f3n. Paso a paso.<\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p lang=\"es\" dir=\"ltr\">En esta semana tendremos la instalaci\u00f3n de la nueva Asamblea. Uno de sus principales motivos a corto plazo son las enmiendas y reformas constitucionales y legales para seguridad y empleo. <a href=\"https:\/\/t.co\/VzCoV9BcNz\">pic.twitter.com\/VzCoV9BcNz<\/a><\/p>&mdash; Washington Delgado L (@wedelgado) <a href=\"https:\/\/twitter.com\/wedelgado\/status\/1922000736629485719?ref_src=twsrc%5Etfw\">May 12, 2025<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<p class=\"wp-block-paragraph\">EDITORIAL DE 92.5 FOREVER RADIO<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">LUNES 12 DE MAYO DE 2025 <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por Washington Delgado L.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es la alternativa que se debe llevar a cabo en la nueva Asamblea Nacional con una mayor\u00eda que se sume solucionar los problemas de inseguridad y pobreza creados por la actual Constituci\u00f3n como dos gestiones y dos objetivos necesarios a corto plazo. Y dejar para el mediano y largo plazo la recuperaci\u00f3n de la institucionalidad [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14991,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[142],"tags":[],"class_list":["post-14990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-editorial"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Enmendar y reformar la Constituci\u00f3n y leyes para reactivar la econom\u00eda y recuperar la paz. - 92.5 FOREVER Radio<\/title>\n<meta name=\"description\" content=\"Es la alternativa que se debe llevar a cabo en la nueva Asamblea Nacional con una mayor\u00eda que se sume solucionar los problemas de inseguridad\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/foreverfutbol.com.ec\/radio\/editorial\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enmendar y reformar la Constituci\u00f3n y leyes para reactivar la econom\u00eda y recuperar la paz. - 92.5 FOREVER Radio\" \/>\n<meta property=\"og:description\" content=\"Es la alternativa que se debe llevar a cabo en la nueva Asamblea Nacional con una mayor\u00eda que se sume solucionar los problemas de inseguridad\" \/>\n<meta property=\"og:url\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/editorial\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\/\" \/>\n<meta property=\"og:site_name\" content=\"92.5 FOREVER Radio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063550693491\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-12T19:57:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-13T22:42:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2025\/05\/image-201-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"669\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Ricardo Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@925forever\" \/>\n<meta name=\"twitter:site\" content=\"@925forever\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/editorial\\\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/editorial\\\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\\\/\"},\"author\":{\"name\":\"Ricardo Rodriguez\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/person\\\/2f679dd16f889ac00df6e7b648062a01\"},\"headline\":\"Enmendar y reformar la Constituci\u00f3n y leyes para reactivar la econom\u00eda y recuperar la paz.\",\"datePublished\":\"2025-05-12T19:57:49+00:00\",\"dateModified\":\"2025-05-13T22:42:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/editorial\\\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\\\/\"},\"wordCount\":1299,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/editorial\\\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/image-201-1.webp\",\"articleSection\":[\"editorial\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/editorial\\\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/editorial\\\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\\\/\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/editorial\\\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\\\/\",\"name\":\"Enmendar y reformar la Constituci\u00f3n y leyes para reactivar la econom\u00eda y recuperar la paz. - 92.5 FOREVER Radio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/editorial\\\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/editorial\\\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/image-201-1.webp\",\"datePublished\":\"2025-05-12T19:57:49+00:00\",\"dateModified\":\"2025-05-13T22:42:00+00:00\",\"description\":\"Es la alternativa que se debe llevar a cabo en la nueva Asamblea Nacional con una mayor\u00eda que se sume solucionar los problemas de inseguridad\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/editorial\\\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/editorial\\\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/editorial\\\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/image-201-1.webp\",\"contentUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/image-201-1.webp\",\"width\":1000,\"height\":669,\"caption\":\"Enmendar y reformar la Constituci\u00f3n y leyes para reactivar la econom\u00eda y recuperar la paz.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/editorial\\\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enmendar y reformar la Constituci\u00f3n y leyes para reactivar la econom\u00eda y recuperar la paz.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\",\"name\":\"92.5 FOREVER Radio\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#organization\",\"name\":\"92.5 FOREVER Radio\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-logo-forever.png\",\"contentUrl\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-logo-forever.png\",\"width\":180,\"height\":154,\"caption\":\"92.5 FOREVER Radio\"},\"image\":{\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100063550693491\",\"https:\\\/\\\/x.com\\\/925forever\",\"https:\\\/\\\/www.instagram.com\\\/radioforever925\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/#\\\/schema\\\/person\\\/2f679dd16f889ac00df6e7b648062a01\",\"name\":\"Ricardo Rodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g\",\"caption\":\"Ricardo Rodriguez\"},\"sameAs\":[\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\"],\"url\":\"https:\\\/\\\/foreverfutbol.com.ec\\\/radio\\\/author\\\/superdmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enmendar y reformar la Constituci\u00f3n y leyes para reactivar la econom\u00eda y recuperar la paz. - 92.5 FOREVER Radio","description":"Es la alternativa que se debe llevar a cabo en la nueva Asamblea Nacional con una mayor\u00eda que se sume solucionar los problemas de inseguridad","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/foreverfutbol.com.ec\/radio\/editorial\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\/","og_locale":"es_ES","og_type":"article","og_title":"Enmendar y reformar la Constituci\u00f3n y leyes para reactivar la econom\u00eda y recuperar la paz. - 92.5 FOREVER Radio","og_description":"Es la alternativa que se debe llevar a cabo en la nueva Asamblea Nacional con una mayor\u00eda que se sume solucionar los problemas de inseguridad","og_url":"https:\/\/foreverfutbol.com.ec\/radio\/editorial\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\/","og_site_name":"92.5 FOREVER Radio","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063550693491","article_published_time":"2025-05-12T19:57:49+00:00","article_modified_time":"2025-05-13T22:42:00+00:00","og_image":[{"width":1000,"height":669,"url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2025\/05\/image-201-1.webp","type":"image\/webp"}],"author":"Ricardo Rodriguez","twitter_card":"summary_large_image","twitter_creator":"@925forever","twitter_site":"@925forever","twitter_misc":{"Escrito por":"Ricardo Rodriguez","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/foreverfutbol.com.ec\/radio\/editorial\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\/#article","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/editorial\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\/"},"author":{"name":"Ricardo Rodriguez","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01"},"headline":"Enmendar y reformar la Constituci\u00f3n y leyes para reactivar la econom\u00eda y recuperar la paz.","datePublished":"2025-05-12T19:57:49+00:00","dateModified":"2025-05-13T22:42:00+00:00","mainEntityOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/editorial\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\/"},"wordCount":1299,"commentCount":0,"publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/editorial\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2025\/05\/image-201-1.webp","articleSection":["editorial"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/foreverfutbol.com.ec\/radio\/editorial\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/foreverfutbol.com.ec\/radio\/editorial\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/editorial\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\/","name":"Enmendar y reformar la Constituci\u00f3n y leyes para reactivar la econom\u00eda y recuperar la paz. - 92.5 FOREVER Radio","isPartOf":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/editorial\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\/#primaryimage"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/editorial\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\/#primaryimage"},"thumbnailUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2025\/05\/image-201-1.webp","datePublished":"2025-05-12T19:57:49+00:00","dateModified":"2025-05-13T22:42:00+00:00","description":"Es la alternativa que se debe llevar a cabo en la nueva Asamblea Nacional con una mayor\u00eda que se sume solucionar los problemas de inseguridad","breadcrumb":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/editorial\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/foreverfutbol.com.ec\/radio\/editorial\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/editorial\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\/#primaryimage","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2025\/05\/image-201-1.webp","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2025\/05\/image-201-1.webp","width":1000,"height":669,"caption":"Enmendar y reformar la Constituci\u00f3n y leyes para reactivar la econom\u00eda y recuperar la paz."},{"@type":"BreadcrumbList","@id":"https:\/\/foreverfutbol.com.ec\/radio\/editorial\/enmendar-y-reformar-la-constitucion-y-leyes-para-reactivar-la-economia-y-recuperar-la-paz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/foreverfutbol.com.ec\/radio\/"},{"@type":"ListItem","position":2,"name":"Enmendar y reformar la Constituci\u00f3n y leyes para reactivar la econom\u00eda y recuperar la paz."}]},{"@type":"WebSite","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#website","url":"https:\/\/foreverfutbol.com.ec\/radio\/","name":"92.5 FOREVER Radio","description":"","publisher":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/foreverfutbol.com.ec\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#organization","name":"92.5 FOREVER Radio","url":"https:\/\/foreverfutbol.com.ec\/radio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","contentUrl":"https:\/\/foreverfutbol.com.ec\/radio\/wp-content\/uploads\/2024\/01\/cropped-logo-forever.png","width":180,"height":154,"caption":"92.5 FOREVER Radio"},"image":{"@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063550693491","https:\/\/x.com\/925forever","https:\/\/www.instagram.com\/radioforever925\/"]},{"@type":"Person","@id":"https:\/\/foreverfutbol.com.ec\/radio\/#\/schema\/person\/2f679dd16f889ac00df6e7b648062a01","name":"Ricardo Rodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5d9dfb95700bd0c503ed088d29de94822b5cc66a74cb0362774e6fc534823d07?s=96&d=mm&r=g","caption":"Ricardo Rodriguez"},"sameAs":["https:\/\/foreverfutbol.com.ec\/radio"],"url":"https:\/\/foreverfutbol.com.ec\/radio\/author\/superdmin\/"}]}},"_links":{"self":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/14990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/comments?post=14990"}],"version-history":[{"count":2,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/14990\/revisions"}],"predecessor-version":[{"id":15080,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/posts\/14990\/revisions\/15080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media\/14991"}],"wp:attachment":[{"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/media?parent=14990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/categories?post=14990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/foreverfutbol.com.ec\/radio\/wp-json\/wp\/v2\/tags?post=14990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}